{"id":63,"date":"2024-09-27T12:09:58","date_gmt":"2024-09-27T12:09:58","guid":{"rendered":"https:\/\/doria-grand-hotel.ms2.decms.eu\/?page_id=63"},"modified":"2024-09-27T12:13:52","modified_gmt":"2024-09-27T12:13:52","slug":"%e9%9a%90%e7%a7%81%e6%94%bf%e7%ad%96","status":"publish","type":"page","link":"https:\/\/www.doriagrandhotel.it\/zh-hans\/%e9%9a%90%e7%a7%81%e6%94%bf%e7%ad%96\/","title":{"rendered":"\u9690\u79c1\u653f\u7b56"},"content":{"rendered":"<p><strong>INFORMAZIONI SUL TRATTAMENTO DEI DATI PERSONALI<br \/>\ndegli utenti che consultano il sito web del Doria Grand Hotel di Milano \u00a0<\/strong><\/p>\n<p><strong>ai sensi dell\u2019articolo 13 del D. Lgs. 196\/03 e del Regolamento (UE) 2016\/679<\/strong><\/p>\n<p>In questa pagina si descrivono le modalit\u00e0 di gestione del sito in riferimento al trattamento dei dati personali degli utenti che lo consultano ed alla loro riservatezza. Si tratta di un\u2019informativa che \u00e8 resa anche ai sensi dell\u2019art. 13 del D. Lgs. n. 196\/2003 e del Regolamento Europeo 679\/2016 \u2013 normativa in materia di Protezione dei Dati Personali, a coloro che interagiscono con i servizi web del Doria Grand Hotel di Milano, accessibili per via telematica a partire dall\u2019indirizzo:<\/p>\n<p><a href=\"https:\/\/www.doriagrandhotel.it\/\">www.doriagrandhotel.it<\/a><\/p>\n<p>corrispondente alla pagina iniziale del sito Doria Grand Hotel, Viale Andrea Doria 22, 20124 Milano<\/p>\n<p>L\u2019informativa \u00e8 resa solo per il presente sito e non anche per altri siti web eventualmente consultati dall\u2019utente tramite link.<\/p>\n<p>IL \u201cTITOLARE\u201d DEL TRATTAMENTO<\/p>\n<p>A seguito della consultazione di questo sito possono essere trattati dati relativi a persone identificate o identificabili. \u201cTitolari del trattamento dei dati personali\u201d eventualmente trattati a seguito della consultazione del nostro sito e di ogni altro dato utilizzato per la fornitura dei nostri servizi, sono Eurofinanziaria Spa, Viale A. Doria, 22 \u2013 20124 Milano per i dati trattati dal Doria Grand Hotel Viale A. Doria, 22 \u2013 20124 Milano<\/p>\n<p>LUOGO DI TRATTAMENTO DEI DATI<\/p>\n<p>I trattamenti connessi ai servizi web di questo sito [fisicamente posto \u201cin hosting\u201d presso la Fastbooking (\u201cwww.fastbooking.com\u201d)] su server in Irlanda hanno luogo presso la predetta sede e sono curati solo da personale tecnico\u00a0<em>dell\u2019Ufficio incaricato del trattamento, oppure da eventuali incaricati di occasionali operazioni di manutenzione<\/em>.<\/p>\n<p>I dati personali forniti dagli utenti che inoltrano richieste di prenotazione alberghiera o invio di materiale informativo (informazioni, newsletter, registrazioni, ecc.) sono utilizzati al solo fine di eseguire il servizio o la prestazione richiesta e non sono comunicati a terzi, tranne i seguenti possibili casi:<\/p>\n<ul>\n<li>partners commerciali del Doria Grand Hotel ai quali lo stesso comunica i dati esclusivamente per evadere le prenotazioni on line, tra cui Fastbooking, Tour Sequana, 82 Rue Henri Farman 92130 Issy-les-Moulineaux, France.<\/li>\n<li>persone societ\u00e0 o studi professionali che prestino attivit\u00e0 di assistenza e consulenza al Doria Grand Hotel in materia contabile, amministrativa, legale, tributaria e finanziaria;<\/li>\n<li>soggetti cui la facolt\u00e0 di accedere ai dati sia riconosciuta da disposizioni di legge o da ordini delle autorit\u00e0;<\/li>\n<\/ul>\n<p>TIPI DI DATI TRATTATI<\/p>\n<p>Dati di navigazione<\/p>\n<p>I sistemi informatici e le procedure software preposte al funzionamento di questo sito web acquisiscono, nel corso del loro normale esercizio, alcuni dati personali la cui trasmissione \u00e8 implicita nell\u2019uso dei protocolli di comunicazione di Internet. Si tratta di informazioni che non sono raccolte per essere associate a interessati identificati, ma che per loro stessa natura potrebbero, attraverso elaborazioni ed associazioni con dati detenuti da terzi, permettere di identificare gli utenti. In questa categoria di dati rientrano gli indirizzi IP o i nomi a dominio dei computer utilizzati dagli utenti che si connettono al sito, gli indirizzi in notazione URI (Uniform Resource Identifier) delle risorse richieste, l\u2019orario della richiesta, il metodo utilizzato nel sottoporre la richiesta al server, la dimensione del file ottenuto in risposta, il codice numerico indicante lo stato della risposta data dal server (buon fine, errore, ecc.) ed altri parametri relativi al sistema operativo e all\u2019ambiente informatico dell\u2019utente. Questi dati vengono utilizzati al solo fine di ricavare informazioni statistiche anonime sull\u2019uso del sito e per controllarne il corretto funzionamento e vengono cancellati immediatamente dopo l\u2019elaborazione. I dati potrebbero essere utilizzati per l\u2019accertamento di responsabilit\u00e0 in caso di ipotetici reati informatici ai danni del sito: salva questa eventualit\u00e0, allo stato i dati sui contatti web non persistono per pi\u00f9 di sette giorni.<\/p>\n<p>Dati forniti volontariamente dall\u2019utente<\/p>\n<p>L\u2019invio facoltativo, esplicito e volontario di posta elettronica agli indirizzi indicati su questo sito comporta la successiva acquisizione dell\u2019indirizzo del mittente, necessario per rispondere alle richieste, nonch\u00e9 degli eventuali altri dati personali inseriti nella missiva. I dati saranno conservati solamente per l\u2019iscrizione richiesta all\u2019invio di newsletter o offerte speciali e non saranno comunicati a nessuno.<\/p>\n<p>Non si raccolgono n\u00e9 utilizzano le informazioni personali relative a chi visita il sito Web. I visitatori rimangono anonimi. L\u2019unica eccezione riguarda le informazioni per l\u2019identificazione personale necessarie per ottemperare agli obblighi contrattuali di prenotazione nei confronti dell\u2019utente.<\/p>\n<p>Prenotazioni<\/p>\n<p>In caso di prenotazione sul sito Web, l\u2019utente \u00e8 tenuto a fornire il proprio nome, indirizzo per la fatturazione, indirizzo e-mail e informazioni sulle modalit\u00e0 di pagamento e sulla carta di credito. I titolari del trattamento utilizzeranno tali informazioni soltanto per l\u2019elaborazione della prenotazione e per inviare informazioni specifiche rilevanti per la conferma della stessa, come la ricevuta, il codice di prenotazione e le condizioni.<\/p>\n<p>Le informazioni fornite non verranno utilizzate a fini commerciali e non verranno vendute, trasmesse, concesse in licenza o inoltrate a terzi in altro modo, ad eccezione del nostro fornitore di servizi di prenotazione Fastbooking per esclusive finalit\u00e0 di prenotazione In ogni caso l\u2019amministratore del sito assicura l\u2019adozione di scrupolose procedure per proteggere i dati di navigazione e l\u2019utilizzo di particolari cure per proteggere i dati relativi alla carta di credito forniti in occasione delle prenotazioni on line.<\/p>\n<p>Gestione Dati Personali Raccolti da Curriculum Vitae Personali<\/p>\n<p>Il Doria Grand Hotel accetta i Curriculum Vitae personali di eventuali candidati via mail in formato elettronico. L\u2019invio spontaneo e volontario del Curriculum sar\u00e0 considerato implicitamente quale consenso informato dalla presente rilasciato dall\u2019interessato alla ricezione ed al trattamento dei dati personali ivi riportati seguendo esclusivamente la finalit\u00e0 legata alla selezione dei potenziali candidati.<\/p>\n<p>I dati trattati al fine della selezione dei candidati sono di tipo personale utile alla ricerca del particolare profilo richiesto. In generale la natura dei dati personali \u00e8 di tipo normale, tranne in alcuni eventuali casi ove si possono indicare dati sensibili necessari all\u2019individuazione di particolari requisiti previsti dalle normative in vigore, come l\u2019indicazione a particolari categorie protette, l\u2019idoneit\u00e0 a determinati lavori e\/o avviamenti obbligatori, nel rispetto dei limiti indicati dalle Autorizzazioni Generali del Garante n. 1 e 2 del 15 dicembre 2016 (Reg. Provv. n. 523 del 15 dicembre 2016 Pubblicato sulla Gazzetta Ufficiale n. 303 del 29 dicembre 2016);<\/p>\n<p>Il conferimento dei dati relativo alla selezione dei candidati \u00e8 obbligatorio. L\u2019eventuale rifiuto di fornire tali dati comporta l\u2019impossibilit\u00e0 di effettuare una regolare attivit\u00e0 di selezione e la eventuale assunzione. I dati in argomento non saranno comunicati a nessuno.<\/p>\n<p>Norme Generali per l\u2019invio del Curriculum Vitae<\/p>\n<p>Gli eventuali Curriculum Vitae ricevuti spontaneamente, in risposta ad un annuncio oppure ad una Nostra richiesta verranno archiviati direttamente da appositi incaricati del trattamento dati personali secondo le direttive di sicurezza dei dati personali adottate nel rispetto delle misure minime di sicurezza di cui al Capitolo V Capo I e II del Codice 196\/03 e del Capo IV Sez 2 del RGPD 679\/2016. Questi verranno stampati solo in occasione di un incontro e colloquio con l\u2019interessato. Dopo il colloquio di lavoro, se il candidato non sar\u00e0 selezionato, il CV sar\u00e0 cancellato e\/o distrutto.<\/p>\n<p>In tutti gli altri casi, trascorso un periodo di tempo breve e dopo aver effettuato i colloqui ed aver superato il periodo di prova, (60 gg )\u00a0 i C.V. vengono cancellati dal computer e se gi\u00e0 stampati vengono distrutti.<\/p>\n<p>Per l\u2019invio dei Curriculum Vitae utilizzare solo i seguenti indirizzi e-mail:<\/p>\n<p>amministrazione@doriagrandhotel.it \u2013 c.a. Responsabile del personale<\/p>\n<p>PERIODO DI CONSERVAZIONE DEI DATI O CRITERI PER DETERMINARE IL PERIODO<\/p>\n<p>Nel rispetto di quanto previsto dall\u2019art. 5 comma 1 lett. e) del Reg. UE 2016\/679 i dati personali raccolti verranno conservati in una forma che consenta l\u2019identificazione degli interessati per un arco di tempo non superiore al conseguimento delle finalit\u00e0 per le quali i dati personali sono trattati.<\/p>\n<p>I tempi di conservazione dei dati di natura personale forniti tramite il sito web dipendono dalla finalit\u00e0 del trattamento effettuato, in particolare:<\/p>\n<ul>\n<li>finalit\u00e0 relative ai dati tecnici di navigazione per il corretto funzionamento del sito web: conservazione solo per la relativa sessione, al termine della quale i dati vengono cancellati;<\/li>\n<li>finalit\u00e0 di riscontro alla richiesta di informazioni\/fornitura di servizi richiesti (massimo 12 mesi per richiesta di contatto; 10 anni per la eventuale documentazione amministrativo\/contabile\/finanziaria relativa alla fornitura di un servizio);<\/li>\n<li>raccolta dati per selezione del personale (massimo 24 mesi);<\/li>\n<li>newsletter, marketing o comunicazioni promozionali in genere via e-mail (fino a revoca del consenso);<\/li>\n<li>finalit\u00e0 di gestione amministrativa-contabile: 10 anni come da termini di legge per la conservazione della documentazione amministrativo\/contabile\/finanziaria.<\/li>\n<\/ul>\n<p>COOKIES<\/p>\n<p>Nessun dato personale degli utenti viene in proposito acquisito dal sito. Non viene fatto uso di cookies per la trasmissione di informazioni di carattere personale, n\u00e9 vengono utilizzati c.d. cookies persistenti di alcun tipo, ovvero sistemi per il tracciamento degli utenti. L\u2019uso di c.d. cookies di sessione (che non vengono memorizzati in modo persistente sul computer dell\u2019utente e svaniscono con la chiusura del browser) \u00e8 strettamente limitato alla trasmissione di identificativi di sessione (costituiti da numeri casuali generati dal server) necessari per consentire l\u2019esplorazione sicura ed efficiente del sito. I c.d. cookies di sessione utilizzati in questo sito evitano il ricorso ad altre tecniche informatiche potenzialmente pregiudizievoli per la riservatezza della navigazione degli utenti e non consentono l\u2019acquisizione di dati personali identificativi dell\u2019utente.<\/p>\n<p>FACOLTATIVITA\u2019 DEL CONFERIMENTO DEI DATI<\/p>\n<p>A parte quanto specificato per i dati di navigazione, l\u2019utente \u00e8 libero di fornire i dati personali riportati nei moduli di richiesta del Doria Grand Hotel o comunque indicati in contatti con l\u2019Ufficio per effettuare delle prenotazioni on line, sollecitare l\u2019invio di materiale informativo o di altre comunicazioni. Il loro mancato conferimento pu\u00f2 comportare l\u2019impossibilit\u00e0 di ottenere quanto richiesto.<\/p>\n<p>MODALITA\u2019 DEL TRATTAMENTO<\/p>\n<p>I dati personali sono trattati con strumenti automatizzati per il tempo strettamente necessario a conseguire gli scopi per cui sono stati raccolti. Specifiche misure di sicurezza sono osservate per prevenire la perdita dei dati, usi illeciti o non corretti ed accessi non autorizzati.<\/p>\n<p>DIRITTI DEGLI INTERESSATI<\/p>\n<p>Come previsto dall\u2019articolo 7 della legge 196\/03 e dal Capo III del GDPR 679\/2016, i soggetti cui si riferiscono i dati personali hanno il diritto di chiedere conferma dell\u2019esistenza di dati che li riguardano e delle logiche di trattamento cui sono sottoposti, il diritto di chiederne l\u2019integrazione, il diritto di opporsi alloro trattamento per motivi legittimi, nonch\u00e9 il diritto di chiederne la rettifica, l\u2019aggiornamento, la cancellazione (Oblio) o il blocco se trattati in violazione della legge, il diritto di ottenere una copia dei dati personali oggetto di trattamento, il diritto alla portabilit\u00e0 dei dati stessi, presentando apposita istanza. Le richieste vanno rivolte a Eurofinanziaria Spa, Viale A Doria,22 \u2013\u00a0 20124 MILANO \u2013 Doria Grand Hotel.<\/p>\n<p>DIRITTO DI RECLAMO<\/p>\n<p>Gli interessati che ritengono che il trattamento dei dati personali a loro riferiti effettuato attraverso questo sito avvenga in violazione di quanto previsto dal Regolamento hanno il diritto di proporre reclamo al Garante, come previsto dall\u2019art. 77 del Regolamento stesso, o di adire le opportune sedi giudiziarie (art. 79 del Regolamento).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>INFORMAZIONI SUL TRATTAMENTO DEI DATI PERSONALI degli u [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"parent":0,"menu_order":900,"comment_status":"closed","ping_status":"closed","template":"template-default-4.php","meta":{"footnotes":""},"class_list":["post-63","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u9690\u79c1\u653f\u7b56 - Doria Grand Hotel<\/title>\n<meta name=\"description\" content=\"INFORMAZIONI SUL TRATTAMENTO DEI DATI PERSONALI degli utenti che consultano il sito web del Doria Grand Hotel di Milano \u00a0  ai sensi dell\u2019articolo 13 del D. Lgs. 196\/03 e del Regolamento (UE) 2016\/679  In questa pagina si descrivono le modalit\u00e0 di gestione del sito in riferimento al trattamento dei dati personali degli utenti che lo consultano ed alla loro riservatezza. Si tratta di un\u2019informativa che \u00e8 resa anche ai sensi dell\u2019art. 13 del D. Lgs. n. 196\/2003 e del Regolamento Europeo 679\/2016 \u2013 normativa in materia di Protezione dei Dati Personali, a coloro che interagiscono con i servizi web del Doria Grand Hotel di Milano, accessibili per via telematica a partire dall\u2019indirizzo:  www.doriagrandhotel.it  corrispondente alla pagina iniziale del sito Doria Grand Hotel, Viale Andrea Doria 22, 20124 Milano  L\u2019informativa \u00e8 resa solo per il presente sito e non anche per altri siti web eventualmente consultati dall\u2019utente tramite link.  IL \u201cTITOLARE\u201d DEL TRATTAMENTO  A seguito della consultazione di questo sito possono essere trattati dati relativi a persone identificate o identificabili. \u201cTitolari del trattamento dei dati personali\u201d eventualmente trattati a seguito della consultazione del nostro sito e di ogni altro dato utilizzato per la fornitura dei nostri servizi, sono Eurofinanziaria Spa, Viale A. Doria, 22 \u2013 20124 Milano per i dati trattati dal Doria Grand Hotel Viale A. Doria, 22 \u2013 20124 Milano  LUOGO DI TRATTAMENTO DEI DATI  I trattamenti connessi ai servizi web di questo sito [fisicamente posto \u201cin hosting\u201d presso la Fastbooking (\u201cwww.fastbooking.com\u201d)] su server in Irlanda hanno luogo presso la predetta sede e sono curati solo da personale tecnico\u00a0dell\u2019Ufficio incaricato del trattamento, oppure da eventuali incaricati di occasionali operazioni di manutenzione.  I dati personali forniti dagli utenti che inoltrano richieste di prenotazione alberghiera o invio di materiale informativo (informazioni, newsletter, registrazioni, ecc.) sono utilizzati al solo fine di eseguire il servizio o la prestazione richiesta e non sono comunicati a terzi, tranne i seguenti possibili casi:   partners commerciali del Doria Grand Hotel ai quali lo stesso comunica i dati esclusivamente per evadere le prenotazioni on line, tra cui Fastbooking, Tour Sequana, 82 Rue Henri Farman 92130 Issy-les-Moulineaux, France.  persone societ\u00e0 o studi professionali che prestino attivit\u00e0 di assistenza e consulenza al Doria Grand Hotel in materia contabile, amministrativa, legale, tributaria e finanziaria;  soggetti cui la facolt\u00e0 di accedere ai dati sia riconosciuta da disposizioni di legge o da ordini delle autorit\u00e0;  TIPI DI DATI TRATTATI  Dati di navigazione  I sistemi informatici e le procedure software preposte al funzionamento di questo sito web acquisiscono, nel corso del loro normale esercizio, alcuni dati personali la cui trasmissione \u00e8 implicita nell\u2019uso dei protocolli di comunicazione di Internet. Si tratta di informazioni che non sono raccolte per essere associate a interessati identificati, ma che per loro stessa natura potrebbero, attraverso elaborazioni ed associazioni con dati detenuti da terzi, permettere di identificare gli utenti. In questa categoria di dati rientrano gli indirizzi IP o i nomi a dominio dei computer utilizzati dagli utenti che si connettono al sito, gli indirizzi in notazione URI (Uniform Resource Identifier) delle risorse richieste, l\u2019orario della richiesta, il metodo utilizzato nel sottoporre la richiesta al server, la dimensione del file ottenuto in risposta, il codice numerico indicante lo stato della risposta data dal server (buon fine, errore, ecc.) ed altri parametri relativi al sistema operativo e all\u2019ambiente informatico dell\u2019utente. Questi dati vengono utilizzati al solo fine di ricavare informazioni statistiche anonime sull\u2019uso del sito e per controllarne il corretto funzionamento e vengono cancellati immediatamente dopo l\u2019elaborazione. I dati potrebbero essere utilizzati per l\u2019accertamento di responsabilit\u00e0 in caso di ipotetici reati informatici ai danni del sito: salva questa eventualit\u00e0, allo stato i dati sui contatti web non persistono per pi\u00f9 di sette giorni.  Dati forniti volontariamente dall\u2019utente  L\u2019invio facoltativo, esplicito e volontario di posta elettronica agli indirizzi indicati su questo sito comporta la successiva acquisizione dell\u2019indirizzo del mittente, necessario per rispondere alle richieste, nonch\u00e9 degli eventuali altri dati personali inseriti nella missiva. I dati saranno conservati solamente per l\u2019iscrizione richiesta all\u2019invio di newsletter o offerte speciali e non saranno comunicati a nessuno.  Non si raccolgono n\u00e9 utilizzano le informazioni personali relative a chi visita il sito Web. I visitatori rimangono anonimi. L\u2019unica eccezione riguarda le informazioni per l\u2019identificazione personale necessarie per ottemperare agli obblighi contrattuali di prenotazione nei confronti dell\u2019utente.  Prenotazioni  In caso di prenotazione sul sito Web, l\u2019utente \u00e8 tenuto a fornire il proprio nome, indirizzo per la fatturazione, indirizzo e-mail e informazioni sulle modalit\u00e0 di pagamento e sulla carta di credito. I titolari del trattamento utilizzeranno tali informazioni soltanto per l\u2019elaborazione della prenotazione e per inviare informazioni specifiche rilevanti per la conferma della stessa, come la ricevuta, il codice di prenotazione e le condizioni.  Le informazioni fornite non verranno utilizzate a fini commerciali e non verranno vendute, trasmesse, concesse in licenza o inoltrate a terzi in altro modo, ad eccezione del nostro fornitore di servizi di prenotazione Fastbooking per esclusive finalit\u00e0 di prenotazione In ogni caso l\u2019amministratore del sito assicura l\u2019adozione di scrupolose procedure per proteggere i dati di navigazione e l\u2019utilizzo di particolari cure per proteggere i dati relativi alla carta di credito forniti in occasione delle prenotazioni on line.  Gestione Dati Personali Raccolti da Curriculum Vitae Personali  Il Doria Grand Hotel accetta i Curriculum Vitae personali di eventuali candidati via mail in formato elettronico. L\u2019invio spontaneo e volontario del Curriculum sar\u00e0 considerato implicitamente quale consenso informato dalla presente rilasciato dall\u2019interessato alla ricezione ed al trattamento dei dati personali ivi riportati seguendo esclusivamente la finalit\u00e0 legata alla selezione dei potenziali candidati.  I dati trattati al fine della selezione dei candidati sono di tipo personale utile alla ricerca del particolare profilo richiesto. In generale la natura dei dati personali \u00e8 di tipo normale, tranne in alcuni eventuali casi ove si possono indicare dati sensibili necessari all\u2019individuazione di particolari requisiti previsti dalle normative in vigore, come l\u2019indicazione a particolari categorie protette, l\u2019idoneit\u00e0 a determinati lavori e\/o avviamenti obbligatori, nel rispetto dei limiti indicati dalle Autorizzazioni Generali del Garante n. 1 e 2 del 15 dicembre 2016 (Reg. Provv. n. 523 del 15 dicembre 2016 Pubblicato sulla Gazzetta Ufficiale n. 303 del 29 dicembre 2016);  Il conferimento dei dati relativo alla selezione dei candidati \u00e8 obbligatorio. L\u2019eventuale rifiuto di fornire tali dati comporta l\u2019impossibilit\u00e0 di effettuare una regolare attivit\u00e0 di selezione e la eventuale assunzione. I dati in argomento non saranno comunicati a nessuno.  Norme Generali per l\u2019invio del Curriculum Vitae  Gli eventuali Curriculum Vitae ricevuti spontaneamente, in risposta ad un annuncio oppure ad una Nostra richiesta verranno archiviati direttamente da appositi incaricati del trattamento dati personali secondo le direttive di sicurezza dei dati personali adottate nel rispetto delle misure minime di sicurezza di cui al Capitolo V Capo I e II del Codice 196\/03 e del Capo IV Sez 2 del RGPD 679\/2016. Questi verranno stampati solo in occasione di un incontro e colloquio con l\u2019interessato. Dopo il colloquio di lavoro, se il candidato non sar\u00e0 selezionato, il CV sar\u00e0 cancellato e\/o distrutto.  In tutti gli altri casi, trascorso un periodo di tempo breve e dopo aver effettuato i colloqui ed aver superato il periodo di prova, (60 gg )\u00a0 i C.V. vengono cancellati dal computer e se gi\u00e0 stampati vengono distrutti.  Per l\u2019invio dei Curriculum Vitae utilizzare solo i seguenti indirizzi e-mail:  amministrazione@doriagrandhotel.it \u2013 c.a. Responsabile del personale  PERIODO DI CONSERVAZIONE DEI DATI O CRITERI PER DETERMINARE IL PERIODO  Nel rispetto di quanto previsto dall\u2019art. 5 comma 1 lett. e) del Reg. UE 2016\/679 i dati personali raccolti verranno conservati in una forma che consenta l\u2019identificazione degli interessati per un arco di tempo non superiore al conseguimento delle finalit\u00e0 per le quali i dati personali sono trattati.  I tempi di conservazione dei dati di natura personale forniti tramite il sito web dipendono dalla finalit\u00e0 del trattamento effettuato, in particolare:   finalit\u00e0 relative ai dati tecnici di navigazione per il corretto funzionamento del sito web: conservazione solo per la relativa sessione, al termine della quale i dati vengono cancellati;  finalit\u00e0 di riscontro alla richiesta di informazioni\/fornitura di servizi richiesti (massimo 12 mesi per richiesta di contatto; 10 anni per la eventuale documentazione amministrativo\/contabile\/finanziaria relativa alla fornitura di un servizio);  raccolta dati per selezione del personale (massimo 24 mesi);  newsletter, marketing o comunicazioni promozionali in genere via e-mail (fino a revoca del consenso);  finalit\u00e0 di gestione amministrativa-contabile: 10 anni come da termini di legge per la conservazione della documentazione amministrativo\/contabile\/finanziaria.  COOKIES  Nessun dato personale degli utenti viene in proposito acquisito dal sito. Non viene fatto uso di cookies per la trasmissione di informazioni di carattere personale, n\u00e9 vengono utilizzati c.d. cookies persistenti di alcun tipo, ovvero sistemi per il tracciamento degli utenti. L\u2019uso di c.d. cookies di sessione (che non vengono memorizzati in modo persistente sul computer dell\u2019utente e svaniscono con la chiusura del browser) \u00e8 strettamente limitato alla trasmissione di identificativi di sessione (costituiti da numeri casuali generati dal server) necessari per consentire l\u2019esplorazione sicura ed efficiente del sito. I c.d. cookies di sessione utilizzati in questo sito evitano il ricorso ad altre tecniche informatiche potenzialmente pregiudizievoli per la riservatezza della navigazione degli utenti e non consentono l\u2019acquisizione di dati personali identificativi dell\u2019utente.  FACOLTATIVITA\u2019 DEL CONFERIMENTO DEI DATI  A parte quanto specificato per i dati di navigazione, l\u2019utente \u00e8 libero di fornire i dati personali riportati nei moduli di richiesta del Doria Grand Hotel o comunque indicati in contatti con l\u2019Ufficio per effettuare delle prenotazioni on line, sollecitare l\u2019invio di materiale informativo o di altre comunicazioni. Il loro mancato conferimento pu\u00f2 comportare l\u2019impossibilit\u00e0 di ottenere quanto richiesto.  MODALITA\u2019 DEL TRATTAMENTO  I dati personali sono trattati con strumenti automatizzati per il tempo strettamente necessario a conseguire gli scopi per cui sono stati raccolti. Specifiche misure di sicurezza sono osservate per prevenire la perdita dei dati, usi illeciti o non corretti ed accessi non autorizzati.  DIRITTI DEGLI INTERESSATI  Come previsto dall\u2019articolo 7 della legge 196\/03 e dal Capo III del GDPR 679\/2016, i soggetti cui si riferiscono i dati personali hanno il diritto di chiedere conferma dell\u2019esistenza di dati che li riguardano e delle logiche di trattamento cui sono sottoposti, il diritto di chiederne l\u2019integrazione, il diritto di opporsi alloro trattamento per motivi legittimi, nonch\u00e9 il diritto di chiederne la rettifica, l\u2019aggiornamento, la cancellazione (Oblio) o il blocco se trattati in violazione della legge, il diritto di ottenere una copia dei dati personali oggetto di trattamento, il diritto alla portabilit\u00e0 dei dati stessi, presentando apposita istanza. Le richieste vanno rivolte a Eurofinanziaria Spa, Viale A Doria,22 \u2013\u00a0 20124 MILANO \u2013 Doria Grand Hotel.  DIRITTO DI RECLAMO  Gli interessati che ritengono che il trattamento dei dati personali a loro riferiti effettuato attraverso questo sito avvenga in violazione di quanto previsto dal Regolamento hanno il diritto di proporre reclamo al Garante, come previsto dall\u2019art. 77 del Regolamento stesso, o di adire le opportune sedi giudiziarie (art. 79 del Regolamento).\u3002\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.doriagrandhotel.it\/zh-hans\/%e9%9a%90%e7%a7%81%e6%94%bf%e7%ad%96\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u9690\u79c1\u653f\u7b56 - Doria Grand Hotel\" \/>\n<meta property=\"og:description\" content=\"INFORMAZIONI SUL TRATTAMENTO DEI DATI PERSONALI degli utenti che consultano il sito web del Doria Grand Hotel di Milano \u00a0  ai sensi dell\u2019articolo 13 del D. Lgs. 196\/03 e del Regolamento (UE) 2016\/679  In questa pagina si descrivono le modalit\u00e0 di gestione del sito in riferimento al trattamento dei dati personali degli utenti che lo consultano ed alla loro riservatezza. Si tratta di un\u2019informativa che \u00e8 resa anche ai sensi dell\u2019art. 13 del D. Lgs. n. 196\/2003 e del Regolamento Europeo 679\/2016 \u2013 normativa in materia di Protezione dei Dati Personali, a coloro che interagiscono con i servizi web del Doria Grand Hotel di Milano, accessibili per via telematica a partire dall\u2019indirizzo:  www.doriagrandhotel.it  corrispondente alla pagina iniziale del sito Doria Grand Hotel, Viale Andrea Doria 22, 20124 Milano  L\u2019informativa \u00e8 resa solo per il presente sito e non anche per altri siti web eventualmente consultati dall\u2019utente tramite link.  IL \u201cTITOLARE\u201d DEL TRATTAMENTO  A seguito della consultazione di questo sito possono essere trattati dati relativi a persone identificate o identificabili. \u201cTitolari del trattamento dei dati personali\u201d eventualmente trattati a seguito della consultazione del nostro sito e di ogni altro dato utilizzato per la fornitura dei nostri servizi, sono Eurofinanziaria Spa, Viale A. Doria, 22 \u2013 20124 Milano per i dati trattati dal Doria Grand Hotel Viale A. Doria, 22 \u2013 20124 Milano  LUOGO DI TRATTAMENTO DEI DATI  I trattamenti connessi ai servizi web di questo sito [fisicamente posto \u201cin hosting\u201d presso la Fastbooking (\u201cwww.fastbooking.com\u201d)] su server in Irlanda hanno luogo presso la predetta sede e sono curati solo da personale tecnico\u00a0dell\u2019Ufficio incaricato del trattamento, oppure da eventuali incaricati di occasionali operazioni di manutenzione.  I dati personali forniti dagli utenti che inoltrano richieste di prenotazione alberghiera o invio di materiale informativo (informazioni, newsletter, registrazioni, ecc.) sono utilizzati al solo fine di eseguire il servizio o la prestazione richiesta e non sono comunicati a terzi, tranne i seguenti possibili casi:   partners commerciali del Doria Grand Hotel ai quali lo stesso comunica i dati esclusivamente per evadere le prenotazioni on line, tra cui Fastbooking, Tour Sequana, 82 Rue Henri Farman 92130 Issy-les-Moulineaux, France.  persone societ\u00e0 o studi professionali che prestino attivit\u00e0 di assistenza e consulenza al Doria Grand Hotel in materia contabile, amministrativa, legale, tributaria e finanziaria;  soggetti cui la facolt\u00e0 di accedere ai dati sia riconosciuta da disposizioni di legge o da ordini delle autorit\u00e0;  TIPI DI DATI TRATTATI  Dati di navigazione  I sistemi informatici e le procedure software preposte al funzionamento di questo sito web acquisiscono, nel corso del loro normale esercizio, alcuni dati personali la cui trasmissione \u00e8 implicita nell\u2019uso dei protocolli di comunicazione di Internet. Si tratta di informazioni che non sono raccolte per essere associate a interessati identificati, ma che per loro stessa natura potrebbero, attraverso elaborazioni ed associazioni con dati detenuti da terzi, permettere di identificare gli utenti. In questa categoria di dati rientrano gli indirizzi IP o i nomi a dominio dei computer utilizzati dagli utenti che si connettono al sito, gli indirizzi in notazione URI (Uniform Resource Identifier) delle risorse richieste, l\u2019orario della richiesta, il metodo utilizzato nel sottoporre la richiesta al server, la dimensione del file ottenuto in risposta, il codice numerico indicante lo stato della risposta data dal server (buon fine, errore, ecc.) ed altri parametri relativi al sistema operativo e all\u2019ambiente informatico dell\u2019utente. Questi dati vengono utilizzati al solo fine di ricavare informazioni statistiche anonime sull\u2019uso del sito e per controllarne il corretto funzionamento e vengono cancellati immediatamente dopo l\u2019elaborazione. I dati potrebbero essere utilizzati per l\u2019accertamento di responsabilit\u00e0 in caso di ipotetici reati informatici ai danni del sito: salva questa eventualit\u00e0, allo stato i dati sui contatti web non persistono per pi\u00f9 di sette giorni.  Dati forniti volontariamente dall\u2019utente  L\u2019invio facoltativo, esplicito e volontario di posta elettronica agli indirizzi indicati su questo sito comporta la successiva acquisizione dell\u2019indirizzo del mittente, necessario per rispondere alle richieste, nonch\u00e9 degli eventuali altri dati personali inseriti nella missiva. I dati saranno conservati solamente per l\u2019iscrizione richiesta all\u2019invio di newsletter o offerte speciali e non saranno comunicati a nessuno.  Non si raccolgono n\u00e9 utilizzano le informazioni personali relative a chi visita il sito Web. I visitatori rimangono anonimi. L\u2019unica eccezione riguarda le informazioni per l\u2019identificazione personale necessarie per ottemperare agli obblighi contrattuali di prenotazione nei confronti dell\u2019utente.  Prenotazioni  In caso di prenotazione sul sito Web, l\u2019utente \u00e8 tenuto a fornire il proprio nome, indirizzo per la fatturazione, indirizzo e-mail e informazioni sulle modalit\u00e0 di pagamento e sulla carta di credito. I titolari del trattamento utilizzeranno tali informazioni soltanto per l\u2019elaborazione della prenotazione e per inviare informazioni specifiche rilevanti per la conferma della stessa, come la ricevuta, il codice di prenotazione e le condizioni.  Le informazioni fornite non verranno utilizzate a fini commerciali e non verranno vendute, trasmesse, concesse in licenza o inoltrate a terzi in altro modo, ad eccezione del nostro fornitore di servizi di prenotazione Fastbooking per esclusive finalit\u00e0 di prenotazione In ogni caso l\u2019amministratore del sito assicura l\u2019adozione di scrupolose procedure per proteggere i dati di navigazione e l\u2019utilizzo di particolari cure per proteggere i dati relativi alla carta di credito forniti in occasione delle prenotazioni on line.  Gestione Dati Personali Raccolti da Curriculum Vitae Personali  Il Doria Grand Hotel accetta i Curriculum Vitae personali di eventuali candidati via mail in formato elettronico. L\u2019invio spontaneo e volontario del Curriculum sar\u00e0 considerato implicitamente quale consenso informato dalla presente rilasciato dall\u2019interessato alla ricezione ed al trattamento dei dati personali ivi riportati seguendo esclusivamente la finalit\u00e0 legata alla selezione dei potenziali candidati.  I dati trattati al fine della selezione dei candidati sono di tipo personale utile alla ricerca del particolare profilo richiesto. In generale la natura dei dati personali \u00e8 di tipo normale, tranne in alcuni eventuali casi ove si possono indicare dati sensibili necessari all\u2019individuazione di particolari requisiti previsti dalle normative in vigore, come l\u2019indicazione a particolari categorie protette, l\u2019idoneit\u00e0 a determinati lavori e\/o avviamenti obbligatori, nel rispetto dei limiti indicati dalle Autorizzazioni Generali del Garante n. 1 e 2 del 15 dicembre 2016 (Reg. Provv. n. 523 del 15 dicembre 2016 Pubblicato sulla Gazzetta Ufficiale n. 303 del 29 dicembre 2016);  Il conferimento dei dati relativo alla selezione dei candidati \u00e8 obbligatorio. L\u2019eventuale rifiuto di fornire tali dati comporta l\u2019impossibilit\u00e0 di effettuare una regolare attivit\u00e0 di selezione e la eventuale assunzione. I dati in argomento non saranno comunicati a nessuno.  Norme Generali per l\u2019invio del Curriculum Vitae  Gli eventuali Curriculum Vitae ricevuti spontaneamente, in risposta ad un annuncio oppure ad una Nostra richiesta verranno archiviati direttamente da appositi incaricati del trattamento dati personali secondo le direttive di sicurezza dei dati personali adottate nel rispetto delle misure minime di sicurezza di cui al Capitolo V Capo I e II del Codice 196\/03 e del Capo IV Sez 2 del RGPD 679\/2016. Questi verranno stampati solo in occasione di un incontro e colloquio con l\u2019interessato. Dopo il colloquio di lavoro, se il candidato non sar\u00e0 selezionato, il CV sar\u00e0 cancellato e\/o distrutto.  In tutti gli altri casi, trascorso un periodo di tempo breve e dopo aver effettuato i colloqui ed aver superato il periodo di prova, (60 gg )\u00a0 i C.V. vengono cancellati dal computer e se gi\u00e0 stampati vengono distrutti.  Per l\u2019invio dei Curriculum Vitae utilizzare solo i seguenti indirizzi e-mail:  amministrazione@doriagrandhotel.it \u2013 c.a. Responsabile del personale  PERIODO DI CONSERVAZIONE DEI DATI O CRITERI PER DETERMINARE IL PERIODO  Nel rispetto di quanto previsto dall\u2019art. 5 comma 1 lett. e) del Reg. UE 2016\/679 i dati personali raccolti verranno conservati in una forma che consenta l\u2019identificazione degli interessati per un arco di tempo non superiore al conseguimento delle finalit\u00e0 per le quali i dati personali sono trattati.  I tempi di conservazione dei dati di natura personale forniti tramite il sito web dipendono dalla finalit\u00e0 del trattamento effettuato, in particolare:   finalit\u00e0 relative ai dati tecnici di navigazione per il corretto funzionamento del sito web: conservazione solo per la relativa sessione, al termine della quale i dati vengono cancellati;  finalit\u00e0 di riscontro alla richiesta di informazioni\/fornitura di servizi richiesti (massimo 12 mesi per richiesta di contatto; 10 anni per la eventuale documentazione amministrativo\/contabile\/finanziaria relativa alla fornitura di un servizio);  raccolta dati per selezione del personale (massimo 24 mesi);  newsletter, marketing o comunicazioni promozionali in genere via e-mail (fino a revoca del consenso);  finalit\u00e0 di gestione amministrativa-contabile: 10 anni come da termini di legge per la conservazione della documentazione amministrativo\/contabile\/finanziaria.  COOKIES  Nessun dato personale degli utenti viene in proposito acquisito dal sito. Non viene fatto uso di cookies per la trasmissione di informazioni di carattere personale, n\u00e9 vengono utilizzati c.d. cookies persistenti di alcun tipo, ovvero sistemi per il tracciamento degli utenti. L\u2019uso di c.d. cookies di sessione (che non vengono memorizzati in modo persistente sul computer dell\u2019utente e svaniscono con la chiusura del browser) \u00e8 strettamente limitato alla trasmissione di identificativi di sessione (costituiti da numeri casuali generati dal server) necessari per consentire l\u2019esplorazione sicura ed efficiente del sito. I c.d. cookies di sessione utilizzati in questo sito evitano il ricorso ad altre tecniche informatiche potenzialmente pregiudizievoli per la riservatezza della navigazione degli utenti e non consentono l\u2019acquisizione di dati personali identificativi dell\u2019utente.  FACOLTATIVITA\u2019 DEL CONFERIMENTO DEI DATI  A parte quanto specificato per i dati di navigazione, l\u2019utente \u00e8 libero di fornire i dati personali riportati nei moduli di richiesta del Doria Grand Hotel o comunque indicati in contatti con l\u2019Ufficio per effettuare delle prenotazioni on line, sollecitare l\u2019invio di materiale informativo o di altre comunicazioni. Il loro mancato conferimento pu\u00f2 comportare l\u2019impossibilit\u00e0 di ottenere quanto richiesto.  MODALITA\u2019 DEL TRATTAMENTO  I dati personali sono trattati con strumenti automatizzati per il tempo strettamente necessario a conseguire gli scopi per cui sono stati raccolti. Specifiche misure di sicurezza sono osservate per prevenire la perdita dei dati, usi illeciti o non corretti ed accessi non autorizzati.  DIRITTI DEGLI INTERESSATI  Come previsto dall\u2019articolo 7 della legge 196\/03 e dal Capo III del GDPR 679\/2016, i soggetti cui si riferiscono i dati personali hanno il diritto di chiedere conferma dell\u2019esistenza di dati che li riguardano e delle logiche di trattamento cui sono sottoposti, il diritto di chiederne l\u2019integrazione, il diritto di opporsi alloro trattamento per motivi legittimi, nonch\u00e9 il diritto di chiederne la rettifica, l\u2019aggiornamento, la cancellazione (Oblio) o il blocco se trattati in violazione della legge, il diritto di ottenere una copia dei dati personali oggetto di trattamento, il diritto alla portabilit\u00e0 dei dati stessi, presentando apposita istanza. Le richieste vanno rivolte a Eurofinanziaria Spa, Viale A Doria,22 \u2013\u00a0 20124 MILANO \u2013 Doria Grand Hotel.  DIRITTO DI RECLAMO  Gli interessati che ritengono che il trattamento dei dati personali a loro riferiti effettuato attraverso questo sito avvenga in violazione di quanto previsto dal Regolamento hanno il diritto di proporre reclamo al Garante, come previsto dall\u2019art. 77 del Regolamento stesso, o di adire le opportune sedi giudiziarie (art. 79 del Regolamento).\u3002\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.doriagrandhotel.it\/zh-hans\/%e9%9a%90%e7%a7%81%e6%94%bf%e7%ad%96\/\" \/>\n<meta property=\"og:site_name\" content=\"Doria Grand Hotel\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Doria-Grand-Hotel-150382741666057\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-27T12:13:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.doriagrandhotel.it\/wp-content\/uploads\/sites\/170\/2024\/11\/Doria-Grand-Hotel-Milan-Exterior.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@adihotels\" \/>\n<meta name=\"twitter:label1\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 \u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.doriagrandhotel.it\\\/zh-hans\\\/%e9%9a%90%e7%a7%81%e6%94%bf%e7%ad%96\\\/\",\"url\":\"https:\\\/\\\/www.doriagrandhotel.it\\\/zh-hans\\\/%e9%9a%90%e7%a7%81%e6%94%bf%e7%ad%96\\\/\",\"name\":\"\u9690\u79c1\u653f\u7b56 - Doria Grand Hotel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.doriagrandhotel.it\\\/zh-hans\\\/#website\"},\"datePublished\":\"2024-09-27T12:09:58+00:00\",\"dateModified\":\"2024-09-27T12:13:52+00:00\",\"description\":\"INFORMAZIONI SUL TRATTAMENTO DEI DATI PERSONALI degli utenti che consultano il sito web del Doria Grand Hotel di Milano \u00a0 ai sensi dell\u2019articolo 13 del D. Lgs. 196\\\/03 e del Regolamento (UE) 2016\\\/679 In questa pagina si descrivono le modalit\u00e0 di gestione del sito in riferimento al trattamento dei dati personali degli utenti che lo consultano ed alla loro riservatezza. Si tratta di un\u2019informativa che \u00e8 resa anche ai sensi dell\u2019art. 13 del D. Lgs. n. 196\\\/2003 e del Regolamento Europeo 679\\\/2016 \u2013 normativa in materia di Protezione dei Dati Personali, a coloro che interagiscono con i servizi web del Doria Grand Hotel di Milano, accessibili per via telematica a partire dall\u2019indirizzo: www.doriagrandhotel.it corrispondente alla pagina iniziale del sito Doria Grand Hotel, Viale Andrea Doria 22, 20124 Milano L\u2019informativa \u00e8 resa solo per il presente sito e non anche per altri siti web eventualmente consultati dall\u2019utente tramite link. IL \u201cTITOLARE\u201d DEL TRATTAMENTO A seguito della consultazione di questo sito possono essere trattati dati relativi a persone identificate o identificabili. \u201cTitolari del trattamento dei dati personali\u201d eventualmente trattati a seguito della consultazione del nostro sito e di ogni altro dato utilizzato per la fornitura dei nostri servizi, sono Eurofinanziaria Spa, Viale A. Doria, 22 \u2013 20124 Milano per i dati trattati dal Doria Grand Hotel Viale A. Doria, 22 \u2013 20124 Milano LUOGO DI TRATTAMENTO DEI DATI I trattamenti connessi ai servizi web di questo sito [fisicamente posto \u201cin hosting\u201d presso la Fastbooking (\u201cwww.fastbooking.com\u201d)] su server in Irlanda hanno luogo presso la predetta sede e sono curati solo da personale tecnico\u00a0dell\u2019Ufficio incaricato del trattamento, oppure da eventuali incaricati di occasionali operazioni di manutenzione. I dati personali forniti dagli utenti che inoltrano richieste di prenotazione alberghiera o invio di materiale informativo (informazioni, newsletter, registrazioni, ecc.) sono utilizzati al solo fine di eseguire il servizio o la prestazione richiesta e non sono comunicati a terzi, tranne i seguenti possibili casi: \u2022 partners commerciali del Doria Grand Hotel ai quali lo stesso comunica i dati esclusivamente per evadere le prenotazioni on line, tra cui Fastbooking, Tour Sequana, 82 Rue Henri Farman 92130 Issy-les-Moulineaux, France. \u2022 persone societ\u00e0 o studi professionali che prestino attivit\u00e0 di assistenza e consulenza al Doria Grand Hotel in materia contabile, amministrativa, legale, tributaria e finanziaria; \u2022 soggetti cui la facolt\u00e0 di accedere ai dati sia riconosciuta da disposizioni di legge o da ordini delle autorit\u00e0; TIPI DI DATI TRATTATI Dati di navigazione I sistemi informatici e le procedure software preposte al funzionamento di questo sito web acquisiscono, nel corso del loro normale esercizio, alcuni dati personali la cui trasmissione \u00e8 implicita nell\u2019uso dei protocolli di comunicazione di Internet. Si tratta di informazioni che non sono raccolte per essere associate a interessati identificati, ma che per loro stessa natura potrebbero, attraverso elaborazioni ed associazioni con dati detenuti da terzi, permettere di identificare gli utenti. In questa categoria di dati rientrano gli indirizzi IP o i nomi a dominio dei computer utilizzati dagli utenti che si connettono al sito, gli indirizzi in notazione URI (Uniform Resource Identifier) delle risorse richieste, l\u2019orario della richiesta, il metodo utilizzato nel sottoporre la richiesta al server, la dimensione del file ottenuto in risposta, il codice numerico indicante lo stato della risposta data dal server (buon fine, errore, ecc.) ed altri parametri relativi al sistema operativo e all\u2019ambiente informatico dell\u2019utente. Questi dati vengono utilizzati al solo fine di ricavare informazioni statistiche anonime sull\u2019uso del sito e per controllarne il corretto funzionamento e vengono cancellati immediatamente dopo l\u2019elaborazione. I dati potrebbero essere utilizzati per l\u2019accertamento di responsabilit\u00e0 in caso di ipotetici reati informatici ai danni del sito: salva questa eventualit\u00e0, allo stato i dati sui contatti web non persistono per pi\u00f9 di sette giorni. Dati forniti volontariamente dall\u2019utente L\u2019invio facoltativo, esplicito e volontario di posta elettronica agli indirizzi indicati su questo sito comporta la successiva acquisizione dell\u2019indirizzo del mittente, necessario per rispondere alle richieste, nonch\u00e9 degli eventuali altri dati personali inseriti nella missiva. I dati saranno conservati solamente per l\u2019iscrizione richiesta all\u2019invio di newsletter o offerte speciali e non saranno comunicati a nessuno. Non si raccolgono n\u00e9 utilizzano le informazioni personali relative a chi visita il sito Web. I visitatori rimangono anonimi. L\u2019unica eccezione riguarda le informazioni per l\u2019identificazione personale necessarie per ottemperare agli obblighi contrattuali di prenotazione nei confronti dell\u2019utente. Prenotazioni In caso di prenotazione sul sito Web, l\u2019utente \u00e8 tenuto a fornire il proprio nome, indirizzo per la fatturazione, indirizzo e-mail e informazioni sulle modalit\u00e0 di pagamento e sulla carta di credito. I titolari del trattamento utilizzeranno tali informazioni soltanto per l\u2019elaborazione della prenotazione e per inviare informazioni specifiche rilevanti per la conferma della stessa, come la ricevuta, il codice di prenotazione e le condizioni. Le informazioni fornite non verranno utilizzate a fini commerciali e non verranno vendute, trasmesse, concesse in licenza o inoltrate a terzi in altro modo, ad eccezione del nostro fornitore di servizi di prenotazione Fastbooking per esclusive finalit\u00e0 di prenotazione In ogni caso l\u2019amministratore del sito assicura l\u2019adozione di scrupolose procedure per proteggere i dati di navigazione e l\u2019utilizzo di particolari cure per proteggere i dati relativi alla carta di credito forniti in occasione delle prenotazioni on line. Gestione Dati Personali Raccolti da Curriculum Vitae Personali Il Doria Grand Hotel accetta i Curriculum Vitae personali di eventuali candidati via mail in formato elettronico. L\u2019invio spontaneo e volontario del Curriculum sar\u00e0 considerato implicitamente quale consenso informato dalla presente rilasciato dall\u2019interessato alla ricezione ed al trattamento dei dati personali ivi riportati seguendo esclusivamente la finalit\u00e0 legata alla selezione dei potenziali candidati. I dati trattati al fine della selezione dei candidati sono di tipo personale utile alla ricerca del particolare profilo richiesto. In generale la natura dei dati personali \u00e8 di tipo normale, tranne in alcuni eventuali casi ove si possono indicare dati sensibili necessari all\u2019individuazione di particolari requisiti previsti dalle normative in vigore, come l\u2019indicazione a particolari categorie protette, l\u2019idoneit\u00e0 a determinati lavori e\\\/o avviamenti obbligatori, nel rispetto dei limiti indicati dalle Autorizzazioni Generali del Garante n. 1 e 2 del 15 dicembre 2016 (Reg. Provv. n. 523 del 15 dicembre 2016 Pubblicato sulla Gazzetta Ufficiale n. 303 del 29 dicembre 2016); Il conferimento dei dati relativo alla selezione dei candidati \u00e8 obbligatorio. L\u2019eventuale rifiuto di fornire tali dati comporta l\u2019impossibilit\u00e0 di effettuare una regolare attivit\u00e0 di selezione e la eventuale assunzione. I dati in argomento non saranno comunicati a nessuno. Norme Generali per l\u2019invio del Curriculum Vitae Gli eventuali Curriculum Vitae ricevuti spontaneamente, in risposta ad un annuncio oppure ad una Nostra richiesta verranno archiviati direttamente da appositi incaricati del trattamento dati personali secondo le direttive di sicurezza dei dati personali adottate nel rispetto delle misure minime di sicurezza di cui al Capitolo V Capo I e II del Codice 196\\\/03 e del Capo IV Sez 2 del RGPD 679\\\/2016. Questi verranno stampati solo in occasione di un incontro e colloquio con l\u2019interessato. Dopo il colloquio di lavoro, se il candidato non sar\u00e0 selezionato, il CV sar\u00e0 cancellato e\\\/o distrutto. In tutti gli altri casi, trascorso un periodo di tempo breve e dopo aver effettuato i colloqui ed aver superato il periodo di prova, (60 gg )\u00a0 i C.V. vengono cancellati dal computer e se gi\u00e0 stampati vengono distrutti. Per l\u2019invio dei Curriculum Vitae utilizzare solo i seguenti indirizzi e-mail: amministrazione@doriagrandhotel.it \u2013 c.a. Responsabile del personale PERIODO DI CONSERVAZIONE DEI DATI O CRITERI PER DETERMINARE IL PERIODO Nel rispetto di quanto previsto dall\u2019art. 5 comma 1 lett. e) del Reg. UE 2016\\\/679 i dati personali raccolti verranno conservati in una forma che consenta l\u2019identificazione degli interessati per un arco di tempo non superiore al conseguimento delle finalit\u00e0 per le quali i dati personali sono trattati. I tempi di conservazione dei dati di natura personale forniti tramite il sito web dipendono dalla finalit\u00e0 del trattamento effettuato, in particolare: \u2022 finalit\u00e0 relative ai dati tecnici di navigazione per il corretto funzionamento del sito web: conservazione solo per la relativa sessione, al termine della quale i dati vengono cancellati; \u2022 finalit\u00e0 di riscontro alla richiesta di informazioni\\\/fornitura di servizi richiesti (massimo 12 mesi per richiesta di contatto; 10 anni per la eventuale documentazione amministrativo\\\/contabile\\\/finanziaria relativa alla fornitura di un servizio); \u2022 raccolta dati per selezione del personale (massimo 24 mesi); \u2022 newsletter, marketing o comunicazioni promozionali in genere via e-mail (fino a revoca del consenso); \u2022 finalit\u00e0 di gestione amministrativa-contabile: 10 anni come da termini di legge per la conservazione della documentazione amministrativo\\\/contabile\\\/finanziaria. COOKIES Nessun dato personale degli utenti viene in proposito acquisito dal sito. Non viene fatto uso di cookies per la trasmissione di informazioni di carattere personale, n\u00e9 vengono utilizzati c.d. cookies persistenti di alcun tipo, ovvero sistemi per il tracciamento degli utenti. L\u2019uso di c.d. cookies di sessione (che non vengono memorizzati in modo persistente sul computer dell\u2019utente e svaniscono con la chiusura del browser) \u00e8 strettamente limitato alla trasmissione di identificativi di sessione (costituiti da numeri casuali generati dal server) necessari per consentire l\u2019esplorazione sicura ed efficiente del sito. I c.d. cookies di sessione utilizzati in questo sito evitano il ricorso ad altre tecniche informatiche potenzialmente pregiudizievoli per la riservatezza della navigazione degli utenti e non consentono l\u2019acquisizione di dati personali identificativi dell\u2019utente. FACOLTATIVITA\u2019 DEL CONFERIMENTO DEI DATI A parte quanto specificato per i dati di navigazione, l\u2019utente \u00e8 libero di fornire i dati personali riportati nei moduli di richiesta del Doria Grand Hotel o comunque indicati in contatti con l\u2019Ufficio per effettuare delle prenotazioni on line, sollecitare l\u2019invio di materiale informativo o di altre comunicazioni. Il loro mancato conferimento pu\u00f2 comportare l\u2019impossibilit\u00e0 di ottenere quanto richiesto. MODALITA\u2019 DEL TRATTAMENTO I dati personali sono trattati con strumenti automatizzati per il tempo strettamente necessario a conseguire gli scopi per cui sono stati raccolti. Specifiche misure di sicurezza sono osservate per prevenire la perdita dei dati, usi illeciti o non corretti ed accessi non autorizzati. DIRITTI DEGLI INTERESSATI Come previsto dall\u2019articolo 7 della legge 196\\\/03 e dal Capo III del GDPR 679\\\/2016, i soggetti cui si riferiscono i dati personali hanno il diritto di chiedere conferma dell\u2019esistenza di dati che li riguardano e delle logiche di trattamento cui sono sottoposti, il diritto di chiederne l\u2019integrazione, il diritto di opporsi alloro trattamento per motivi legittimi, nonch\u00e9 il diritto di chiederne la rettifica, l\u2019aggiornamento, la cancellazione (Oblio) o il blocco se trattati in violazione della legge, il diritto di ottenere una copia dei dati personali oggetto di trattamento, il diritto alla portabilit\u00e0 dei dati stessi, presentando apposita istanza. Le richieste vanno rivolte a Eurofinanziaria Spa, Viale A Doria,22 \u2013\u00a0 20124 MILANO \u2013 Doria Grand Hotel. DIRITTO DI RECLAMO Gli interessati che ritengono che il trattamento dei dati personali a loro riferiti effettuato attraverso questo sito avvenga in violazione di quanto previsto dal Regolamento hanno il diritto di proporre reclamo al Garante, come previsto dall\u2019art. 77 del Regolamento stesso, o di adire le opportune sedi giudiziarie (art. 79 del Regolamento).\u3002\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.doriagrandhotel.it\\\/zh-hans\\\/%e9%9a%90%e7%a7%81%e6%94%bf%e7%ad%96\\\/#breadcrumb\"},\"inLanguage\":\"zh-CN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.doriagrandhotel.it\\\/zh-hans\\\/%e9%9a%90%e7%a7%81%e6%94%bf%e7%ad%96\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.doriagrandhotel.it\\\/zh-hans\\\/%e9%9a%90%e7%a7%81%e6%94%bf%e7%ad%96\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.doriagrandhotel.it\\\/zh-hans\\\/%e6%ac%a2%e8%bf%8e%e6%9d%a5%e5%88%b0%e5%a4%9a%e9%87%8c%e4%ba%9a%e5%a4%a7%e9%85%92%e5%ba%97\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u9690\u79c1\u653f\u7b56\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.doriagrandhotel.it\\\/zh-hans\\\/#website\",\"url\":\"https:\\\/\\\/www.doriagrandhotel.it\\\/zh-hans\\\/\",\"name\":\"Doria Grand Hotel\",\"description\":\"Official website of Doria Grand Hotel , a luxury  hotel in Milan center. Book your hotel in Milan at the best price\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.doriagrandhotel.it\\\/zh-hans\\\/#organization\"},\"alternateName\":\"Doria Grand Hotel\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.doriagrandhotel.it\\\/zh-hans\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-CN\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.doriagrandhotel.it\\\/zh-hans\\\/#organization\",\"name\":\"Doria Grand Hotel\",\"alternateName\":\"Doria Grand Hotel\",\"url\":\"https:\\\/\\\/www.doriagrandhotel.it\\\/zh-hans\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-CN\",\"@id\":\"https:\\\/\\\/www.doriagrandhotel.it\\\/zh-hans\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/doria-grand-hotel.ms2.decms.eu\\\/wp-content\\\/uploads\\\/sites\\\/170\\\/2024\\\/09\\\/LOGO-DGH-tr.png\",\"contentUrl\":\"https:\\\/\\\/doria-grand-hotel.ms2.decms.eu\\\/wp-content\\\/uploads\\\/sites\\\/170\\\/2024\\\/09\\\/LOGO-DGH-tr.png\",\"width\":230,\"height\":51,\"caption\":\"Doria Grand Hotel\"},\"image\":{\"@id\":\"https:\\\/\\\/www.doriagrandhotel.it\\\/zh-hans\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Doria-Grand-Hotel-150382741666057\\\/\",\"https:\\\/\\\/x.com\\\/adihotels\",\"https:\\\/\\\/www.instagram.com\\\/doriagrandhotel\\\/?hl=en\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/doria-grand-hotel\\\/\",\"https:\\\/\\\/www.tripadvisor.com\\\/Hotel_Review-g187849-d202862-Reviews-Doria_Grand_Hotel-Milan_Lombardy.html\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u9690\u79c1\u653f\u7b56 - Doria Grand Hotel","description":"INFORMAZIONI SUL TRATTAMENTO DEI DATI PERSONALI degli utenti che consultano il sito web del Doria Grand Hotel di Milano \u00a0  ai sensi dell\u2019articolo 13 del D. Lgs. 196\/03 e del Regolamento (UE) 2016\/679  In questa pagina si descrivono le modalit\u00e0 di gestione del sito in riferimento al trattamento dei dati personali degli utenti che lo consultano ed alla loro riservatezza. Si tratta di un\u2019informativa che \u00e8 resa anche ai sensi dell\u2019art. 13 del D. Lgs. n. 196\/2003 e del Regolamento Europeo 679\/2016 \u2013 normativa in materia di Protezione dei Dati Personali, a coloro che interagiscono con i servizi web del Doria Grand Hotel di Milano, accessibili per via telematica a partire dall\u2019indirizzo:  www.doriagrandhotel.it  corrispondente alla pagina iniziale del sito Doria Grand Hotel, Viale Andrea Doria 22, 20124 Milano  L\u2019informativa \u00e8 resa solo per il presente sito e non anche per altri siti web eventualmente consultati dall\u2019utente tramite link.  IL \u201cTITOLARE\u201d DEL TRATTAMENTO  A seguito della consultazione di questo sito possono essere trattati dati relativi a persone identificate o identificabili. \u201cTitolari del trattamento dei dati personali\u201d eventualmente trattati a seguito della consultazione del nostro sito e di ogni altro dato utilizzato per la fornitura dei nostri servizi, sono Eurofinanziaria Spa, Viale A. Doria, 22 \u2013 20124 Milano per i dati trattati dal Doria Grand Hotel Viale A. Doria, 22 \u2013 20124 Milano  LUOGO DI TRATTAMENTO DEI DATI  I trattamenti connessi ai servizi web di questo sito [fisicamente posto \u201cin hosting\u201d presso la Fastbooking (\u201cwww.fastbooking.com\u201d)] su server in Irlanda hanno luogo presso la predetta sede e sono curati solo da personale tecnico\u00a0dell\u2019Ufficio incaricato del trattamento, oppure da eventuali incaricati di occasionali operazioni di manutenzione.  I dati personali forniti dagli utenti che inoltrano richieste di prenotazione alberghiera o invio di materiale informativo (informazioni, newsletter, registrazioni, ecc.) sono utilizzati al solo fine di eseguire il servizio o la prestazione richiesta e non sono comunicati a terzi, tranne i seguenti possibili casi:   partners commerciali del Doria Grand Hotel ai quali lo stesso comunica i dati esclusivamente per evadere le prenotazioni on line, tra cui Fastbooking, Tour Sequana, 82 Rue Henri Farman 92130 Issy-les-Moulineaux, France.  persone societ\u00e0 o studi professionali che prestino attivit\u00e0 di assistenza e consulenza al Doria Grand Hotel in materia contabile, amministrativa, legale, tributaria e finanziaria;  soggetti cui la facolt\u00e0 di accedere ai dati sia riconosciuta da disposizioni di legge o da ordini delle autorit\u00e0;  TIPI DI DATI TRATTATI  Dati di navigazione  I sistemi informatici e le procedure software preposte al funzionamento di questo sito web acquisiscono, nel corso del loro normale esercizio, alcuni dati personali la cui trasmissione \u00e8 implicita nell\u2019uso dei protocolli di comunicazione di Internet. Si tratta di informazioni che non sono raccolte per essere associate a interessati identificati, ma che per loro stessa natura potrebbero, attraverso elaborazioni ed associazioni con dati detenuti da terzi, permettere di identificare gli utenti. In questa categoria di dati rientrano gli indirizzi IP o i nomi a dominio dei computer utilizzati dagli utenti che si connettono al sito, gli indirizzi in notazione URI (Uniform Resource Identifier) delle risorse richieste, l\u2019orario della richiesta, il metodo utilizzato nel sottoporre la richiesta al server, la dimensione del file ottenuto in risposta, il codice numerico indicante lo stato della risposta data dal server (buon fine, errore, ecc.) ed altri parametri relativi al sistema operativo e all\u2019ambiente informatico dell\u2019utente. Questi dati vengono utilizzati al solo fine di ricavare informazioni statistiche anonime sull\u2019uso del sito e per controllarne il corretto funzionamento e vengono cancellati immediatamente dopo l\u2019elaborazione. I dati potrebbero essere utilizzati per l\u2019accertamento di responsabilit\u00e0 in caso di ipotetici reati informatici ai danni del sito: salva questa eventualit\u00e0, allo stato i dati sui contatti web non persistono per pi\u00f9 di sette giorni.  Dati forniti volontariamente dall\u2019utente  L\u2019invio facoltativo, esplicito e volontario di posta elettronica agli indirizzi indicati su questo sito comporta la successiva acquisizione dell\u2019indirizzo del mittente, necessario per rispondere alle richieste, nonch\u00e9 degli eventuali altri dati personali inseriti nella missiva. I dati saranno conservati solamente per l\u2019iscrizione richiesta all\u2019invio di newsletter o offerte speciali e non saranno comunicati a nessuno.  Non si raccolgono n\u00e9 utilizzano le informazioni personali relative a chi visita il sito Web. I visitatori rimangono anonimi. L\u2019unica eccezione riguarda le informazioni per l\u2019identificazione personale necessarie per ottemperare agli obblighi contrattuali di prenotazione nei confronti dell\u2019utente.  Prenotazioni  In caso di prenotazione sul sito Web, l\u2019utente \u00e8 tenuto a fornire il proprio nome, indirizzo per la fatturazione, indirizzo e-mail e informazioni sulle modalit\u00e0 di pagamento e sulla carta di credito. I titolari del trattamento utilizzeranno tali informazioni soltanto per l\u2019elaborazione della prenotazione e per inviare informazioni specifiche rilevanti per la conferma della stessa, come la ricevuta, il codice di prenotazione e le condizioni.  Le informazioni fornite non verranno utilizzate a fini commerciali e non verranno vendute, trasmesse, concesse in licenza o inoltrate a terzi in altro modo, ad eccezione del nostro fornitore di servizi di prenotazione Fastbooking per esclusive finalit\u00e0 di prenotazione In ogni caso l\u2019amministratore del sito assicura l\u2019adozione di scrupolose procedure per proteggere i dati di navigazione e l\u2019utilizzo di particolari cure per proteggere i dati relativi alla carta di credito forniti in occasione delle prenotazioni on line.  Gestione Dati Personali Raccolti da Curriculum Vitae Personali  Il Doria Grand Hotel accetta i Curriculum Vitae personali di eventuali candidati via mail in formato elettronico. L\u2019invio spontaneo e volontario del Curriculum sar\u00e0 considerato implicitamente quale consenso informato dalla presente rilasciato dall\u2019interessato alla ricezione ed al trattamento dei dati personali ivi riportati seguendo esclusivamente la finalit\u00e0 legata alla selezione dei potenziali candidati.  I dati trattati al fine della selezione dei candidati sono di tipo personale utile alla ricerca del particolare profilo richiesto. In generale la natura dei dati personali \u00e8 di tipo normale, tranne in alcuni eventuali casi ove si possono indicare dati sensibili necessari all\u2019individuazione di particolari requisiti previsti dalle normative in vigore, come l\u2019indicazione a particolari categorie protette, l\u2019idoneit\u00e0 a determinati lavori e\/o avviamenti obbligatori, nel rispetto dei limiti indicati dalle Autorizzazioni Generali del Garante n. 1 e 2 del 15 dicembre 2016 (Reg. Provv. n. 523 del 15 dicembre 2016 Pubblicato sulla Gazzetta Ufficiale n. 303 del 29 dicembre 2016);  Il conferimento dei dati relativo alla selezione dei candidati \u00e8 obbligatorio. L\u2019eventuale rifiuto di fornire tali dati comporta l\u2019impossibilit\u00e0 di effettuare una regolare attivit\u00e0 di selezione e la eventuale assunzione. I dati in argomento non saranno comunicati a nessuno.  Norme Generali per l\u2019invio del Curriculum Vitae  Gli eventuali Curriculum Vitae ricevuti spontaneamente, in risposta ad un annuncio oppure ad una Nostra richiesta verranno archiviati direttamente da appositi incaricati del trattamento dati personali secondo le direttive di sicurezza dei dati personali adottate nel rispetto delle misure minime di sicurezza di cui al Capitolo V Capo I e II del Codice 196\/03 e del Capo IV Sez 2 del RGPD 679\/2016. Questi verranno stampati solo in occasione di un incontro e colloquio con l\u2019interessato. Dopo il colloquio di lavoro, se il candidato non sar\u00e0 selezionato, il CV sar\u00e0 cancellato e\/o distrutto.  In tutti gli altri casi, trascorso un periodo di tempo breve e dopo aver effettuato i colloqui ed aver superato il periodo di prova, (60 gg )\u00a0 i C.V. vengono cancellati dal computer e se gi\u00e0 stampati vengono distrutti.  Per l\u2019invio dei Curriculum Vitae utilizzare solo i seguenti indirizzi e-mail:  amministrazione@doriagrandhotel.it \u2013 c.a. Responsabile del personale  PERIODO DI CONSERVAZIONE DEI DATI O CRITERI PER DETERMINARE IL PERIODO  Nel rispetto di quanto previsto dall\u2019art. 5 comma 1 lett. e) del Reg. UE 2016\/679 i dati personali raccolti verranno conservati in una forma che consenta l\u2019identificazione degli interessati per un arco di tempo non superiore al conseguimento delle finalit\u00e0 per le quali i dati personali sono trattati.  I tempi di conservazione dei dati di natura personale forniti tramite il sito web dipendono dalla finalit\u00e0 del trattamento effettuato, in particolare:   finalit\u00e0 relative ai dati tecnici di navigazione per il corretto funzionamento del sito web: conservazione solo per la relativa sessione, al termine della quale i dati vengono cancellati;  finalit\u00e0 di riscontro alla richiesta di informazioni\/fornitura di servizi richiesti (massimo 12 mesi per richiesta di contatto; 10 anni per la eventuale documentazione amministrativo\/contabile\/finanziaria relativa alla fornitura di un servizio);  raccolta dati per selezione del personale (massimo 24 mesi);  newsletter, marketing o comunicazioni promozionali in genere via e-mail (fino a revoca del consenso);  finalit\u00e0 di gestione amministrativa-contabile: 10 anni come da termini di legge per la conservazione della documentazione amministrativo\/contabile\/finanziaria.  COOKIES  Nessun dato personale degli utenti viene in proposito acquisito dal sito. Non viene fatto uso di cookies per la trasmissione di informazioni di carattere personale, n\u00e9 vengono utilizzati c.d. cookies persistenti di alcun tipo, ovvero sistemi per il tracciamento degli utenti. L\u2019uso di c.d. cookies di sessione (che non vengono memorizzati in modo persistente sul computer dell\u2019utente e svaniscono con la chiusura del browser) \u00e8 strettamente limitato alla trasmissione di identificativi di sessione (costituiti da numeri casuali generati dal server) necessari per consentire l\u2019esplorazione sicura ed efficiente del sito. I c.d. cookies di sessione utilizzati in questo sito evitano il ricorso ad altre tecniche informatiche potenzialmente pregiudizievoli per la riservatezza della navigazione degli utenti e non consentono l\u2019acquisizione di dati personali identificativi dell\u2019utente.  FACOLTATIVITA\u2019 DEL CONFERIMENTO DEI DATI  A parte quanto specificato per i dati di navigazione, l\u2019utente \u00e8 libero di fornire i dati personali riportati nei moduli di richiesta del Doria Grand Hotel o comunque indicati in contatti con l\u2019Ufficio per effettuare delle prenotazioni on line, sollecitare l\u2019invio di materiale informativo o di altre comunicazioni. Il loro mancato conferimento pu\u00f2 comportare l\u2019impossibilit\u00e0 di ottenere quanto richiesto.  MODALITA\u2019 DEL TRATTAMENTO  I dati personali sono trattati con strumenti automatizzati per il tempo strettamente necessario a conseguire gli scopi per cui sono stati raccolti. Specifiche misure di sicurezza sono osservate per prevenire la perdita dei dati, usi illeciti o non corretti ed accessi non autorizzati.  DIRITTI DEGLI INTERESSATI  Come previsto dall\u2019articolo 7 della legge 196\/03 e dal Capo III del GDPR 679\/2016, i soggetti cui si riferiscono i dati personali hanno il diritto di chiedere conferma dell\u2019esistenza di dati che li riguardano e delle logiche di trattamento cui sono sottoposti, il diritto di chiederne l\u2019integrazione, il diritto di opporsi alloro trattamento per motivi legittimi, nonch\u00e9 il diritto di chiederne la rettifica, l\u2019aggiornamento, la cancellazione (Oblio) o il blocco se trattati in violazione della legge, il diritto di ottenere una copia dei dati personali oggetto di trattamento, il diritto alla portabilit\u00e0 dei dati stessi, presentando apposita istanza. Le richieste vanno rivolte a Eurofinanziaria Spa, Viale A Doria,22 \u2013\u00a0 20124 MILANO \u2013 Doria Grand Hotel.  DIRITTO DI RECLAMO  Gli interessati che ritengono che il trattamento dei dati personali a loro riferiti effettuato attraverso questo sito avvenga in violazione di quanto previsto dal Regolamento hanno il diritto di proporre reclamo al Garante, come previsto dall\u2019art. 77 del Regolamento stesso, o di adire le opportune sedi giudiziarie (art. 79 del Regolamento).\u3002","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.doriagrandhotel.it\/zh-hans\/%e9%9a%90%e7%a7%81%e6%94%bf%e7%ad%96\/","og_locale":"zh_CN","og_type":"article","og_title":"\u9690\u79c1\u653f\u7b56 - Doria Grand Hotel","og_description":"INFORMAZIONI SUL TRATTAMENTO DEI DATI PERSONALI degli utenti che consultano il sito web del Doria Grand Hotel di Milano \u00a0  ai sensi dell\u2019articolo 13 del D. Lgs. 196\/03 e del Regolamento (UE) 2016\/679  In questa pagina si descrivono le modalit\u00e0 di gestione del sito in riferimento al trattamento dei dati personali degli utenti che lo consultano ed alla loro riservatezza. Si tratta di un\u2019informativa che \u00e8 resa anche ai sensi dell\u2019art. 13 del D. Lgs. n. 196\/2003 e del Regolamento Europeo 679\/2016 \u2013 normativa in materia di Protezione dei Dati Personali, a coloro che interagiscono con i servizi web del Doria Grand Hotel di Milano, accessibili per via telematica a partire dall\u2019indirizzo:  www.doriagrandhotel.it  corrispondente alla pagina iniziale del sito Doria Grand Hotel, Viale Andrea Doria 22, 20124 Milano  L\u2019informativa \u00e8 resa solo per il presente sito e non anche per altri siti web eventualmente consultati dall\u2019utente tramite link.  IL \u201cTITOLARE\u201d DEL TRATTAMENTO  A seguito della consultazione di questo sito possono essere trattati dati relativi a persone identificate o identificabili. \u201cTitolari del trattamento dei dati personali\u201d eventualmente trattati a seguito della consultazione del nostro sito e di ogni altro dato utilizzato per la fornitura dei nostri servizi, sono Eurofinanziaria Spa, Viale A. Doria, 22 \u2013 20124 Milano per i dati trattati dal Doria Grand Hotel Viale A. Doria, 22 \u2013 20124 Milano  LUOGO DI TRATTAMENTO DEI DATI  I trattamenti connessi ai servizi web di questo sito [fisicamente posto \u201cin hosting\u201d presso la Fastbooking (\u201cwww.fastbooking.com\u201d)] su server in Irlanda hanno luogo presso la predetta sede e sono curati solo da personale tecnico\u00a0dell\u2019Ufficio incaricato del trattamento, oppure da eventuali incaricati di occasionali operazioni di manutenzione.  I dati personali forniti dagli utenti che inoltrano richieste di prenotazione alberghiera o invio di materiale informativo (informazioni, newsletter, registrazioni, ecc.) sono utilizzati al solo fine di eseguire il servizio o la prestazione richiesta e non sono comunicati a terzi, tranne i seguenti possibili casi:   partners commerciali del Doria Grand Hotel ai quali lo stesso comunica i dati esclusivamente per evadere le prenotazioni on line, tra cui Fastbooking, Tour Sequana, 82 Rue Henri Farman 92130 Issy-les-Moulineaux, France.  persone societ\u00e0 o studi professionali che prestino attivit\u00e0 di assistenza e consulenza al Doria Grand Hotel in materia contabile, amministrativa, legale, tributaria e finanziaria;  soggetti cui la facolt\u00e0 di accedere ai dati sia riconosciuta da disposizioni di legge o da ordini delle autorit\u00e0;  TIPI DI DATI TRATTATI  Dati di navigazione  I sistemi informatici e le procedure software preposte al funzionamento di questo sito web acquisiscono, nel corso del loro normale esercizio, alcuni dati personali la cui trasmissione \u00e8 implicita nell\u2019uso dei protocolli di comunicazione di Internet. Si tratta di informazioni che non sono raccolte per essere associate a interessati identificati, ma che per loro stessa natura potrebbero, attraverso elaborazioni ed associazioni con dati detenuti da terzi, permettere di identificare gli utenti. In questa categoria di dati rientrano gli indirizzi IP o i nomi a dominio dei computer utilizzati dagli utenti che si connettono al sito, gli indirizzi in notazione URI (Uniform Resource Identifier) delle risorse richieste, l\u2019orario della richiesta, il metodo utilizzato nel sottoporre la richiesta al server, la dimensione del file ottenuto in risposta, il codice numerico indicante lo stato della risposta data dal server (buon fine, errore, ecc.) ed altri parametri relativi al sistema operativo e all\u2019ambiente informatico dell\u2019utente. Questi dati vengono utilizzati al solo fine di ricavare informazioni statistiche anonime sull\u2019uso del sito e per controllarne il corretto funzionamento e vengono cancellati immediatamente dopo l\u2019elaborazione. I dati potrebbero essere utilizzati per l\u2019accertamento di responsabilit\u00e0 in caso di ipotetici reati informatici ai danni del sito: salva questa eventualit\u00e0, allo stato i dati sui contatti web non persistono per pi\u00f9 di sette giorni.  Dati forniti volontariamente dall\u2019utente  L\u2019invio facoltativo, esplicito e volontario di posta elettronica agli indirizzi indicati su questo sito comporta la successiva acquisizione dell\u2019indirizzo del mittente, necessario per rispondere alle richieste, nonch\u00e9 degli eventuali altri dati personali inseriti nella missiva. I dati saranno conservati solamente per l\u2019iscrizione richiesta all\u2019invio di newsletter o offerte speciali e non saranno comunicati a nessuno.  Non si raccolgono n\u00e9 utilizzano le informazioni personali relative a chi visita il sito Web. I visitatori rimangono anonimi. L\u2019unica eccezione riguarda le informazioni per l\u2019identificazione personale necessarie per ottemperare agli obblighi contrattuali di prenotazione nei confronti dell\u2019utente.  Prenotazioni  In caso di prenotazione sul sito Web, l\u2019utente \u00e8 tenuto a fornire il proprio nome, indirizzo per la fatturazione, indirizzo e-mail e informazioni sulle modalit\u00e0 di pagamento e sulla carta di credito. I titolari del trattamento utilizzeranno tali informazioni soltanto per l\u2019elaborazione della prenotazione e per inviare informazioni specifiche rilevanti per la conferma della stessa, come la ricevuta, il codice di prenotazione e le condizioni.  Le informazioni fornite non verranno utilizzate a fini commerciali e non verranno vendute, trasmesse, concesse in licenza o inoltrate a terzi in altro modo, ad eccezione del nostro fornitore di servizi di prenotazione Fastbooking per esclusive finalit\u00e0 di prenotazione In ogni caso l\u2019amministratore del sito assicura l\u2019adozione di scrupolose procedure per proteggere i dati di navigazione e l\u2019utilizzo di particolari cure per proteggere i dati relativi alla carta di credito forniti in occasione delle prenotazioni on line.  Gestione Dati Personali Raccolti da Curriculum Vitae Personali  Il Doria Grand Hotel accetta i Curriculum Vitae personali di eventuali candidati via mail in formato elettronico. L\u2019invio spontaneo e volontario del Curriculum sar\u00e0 considerato implicitamente quale consenso informato dalla presente rilasciato dall\u2019interessato alla ricezione ed al trattamento dei dati personali ivi riportati seguendo esclusivamente la finalit\u00e0 legata alla selezione dei potenziali candidati.  I dati trattati al fine della selezione dei candidati sono di tipo personale utile alla ricerca del particolare profilo richiesto. In generale la natura dei dati personali \u00e8 di tipo normale, tranne in alcuni eventuali casi ove si possono indicare dati sensibili necessari all\u2019individuazione di particolari requisiti previsti dalle normative in vigore, come l\u2019indicazione a particolari categorie protette, l\u2019idoneit\u00e0 a determinati lavori e\/o avviamenti obbligatori, nel rispetto dei limiti indicati dalle Autorizzazioni Generali del Garante n. 1 e 2 del 15 dicembre 2016 (Reg. Provv. n. 523 del 15 dicembre 2016 Pubblicato sulla Gazzetta Ufficiale n. 303 del 29 dicembre 2016);  Il conferimento dei dati relativo alla selezione dei candidati \u00e8 obbligatorio. L\u2019eventuale rifiuto di fornire tali dati comporta l\u2019impossibilit\u00e0 di effettuare una regolare attivit\u00e0 di selezione e la eventuale assunzione. I dati in argomento non saranno comunicati a nessuno.  Norme Generali per l\u2019invio del Curriculum Vitae  Gli eventuali Curriculum Vitae ricevuti spontaneamente, in risposta ad un annuncio oppure ad una Nostra richiesta verranno archiviati direttamente da appositi incaricati del trattamento dati personali secondo le direttive di sicurezza dei dati personali adottate nel rispetto delle misure minime di sicurezza di cui al Capitolo V Capo I e II del Codice 196\/03 e del Capo IV Sez 2 del RGPD 679\/2016. Questi verranno stampati solo in occasione di un incontro e colloquio con l\u2019interessato. Dopo il colloquio di lavoro, se il candidato non sar\u00e0 selezionato, il CV sar\u00e0 cancellato e\/o distrutto.  In tutti gli altri casi, trascorso un periodo di tempo breve e dopo aver effettuato i colloqui ed aver superato il periodo di prova, (60 gg )\u00a0 i C.V. vengono cancellati dal computer e se gi\u00e0 stampati vengono distrutti.  Per l\u2019invio dei Curriculum Vitae utilizzare solo i seguenti indirizzi e-mail:  amministrazione@doriagrandhotel.it \u2013 c.a. Responsabile del personale  PERIODO DI CONSERVAZIONE DEI DATI O CRITERI PER DETERMINARE IL PERIODO  Nel rispetto di quanto previsto dall\u2019art. 5 comma 1 lett. e) del Reg. UE 2016\/679 i dati personali raccolti verranno conservati in una forma che consenta l\u2019identificazione degli interessati per un arco di tempo non superiore al conseguimento delle finalit\u00e0 per le quali i dati personali sono trattati.  I tempi di conservazione dei dati di natura personale forniti tramite il sito web dipendono dalla finalit\u00e0 del trattamento effettuato, in particolare:   finalit\u00e0 relative ai dati tecnici di navigazione per il corretto funzionamento del sito web: conservazione solo per la relativa sessione, al termine della quale i dati vengono cancellati;  finalit\u00e0 di riscontro alla richiesta di informazioni\/fornitura di servizi richiesti (massimo 12 mesi per richiesta di contatto; 10 anni per la eventuale documentazione amministrativo\/contabile\/finanziaria relativa alla fornitura di un servizio);  raccolta dati per selezione del personale (massimo 24 mesi);  newsletter, marketing o comunicazioni promozionali in genere via e-mail (fino a revoca del consenso);  finalit\u00e0 di gestione amministrativa-contabile: 10 anni come da termini di legge per la conservazione della documentazione amministrativo\/contabile\/finanziaria.  COOKIES  Nessun dato personale degli utenti viene in proposito acquisito dal sito. Non viene fatto uso di cookies per la trasmissione di informazioni di carattere personale, n\u00e9 vengono utilizzati c.d. cookies persistenti di alcun tipo, ovvero sistemi per il tracciamento degli utenti. L\u2019uso di c.d. cookies di sessione (che non vengono memorizzati in modo persistente sul computer dell\u2019utente e svaniscono con la chiusura del browser) \u00e8 strettamente limitato alla trasmissione di identificativi di sessione (costituiti da numeri casuali generati dal server) necessari per consentire l\u2019esplorazione sicura ed efficiente del sito. I c.d. cookies di sessione utilizzati in questo sito evitano il ricorso ad altre tecniche informatiche potenzialmente pregiudizievoli per la riservatezza della navigazione degli utenti e non consentono l\u2019acquisizione di dati personali identificativi dell\u2019utente.  FACOLTATIVITA\u2019 DEL CONFERIMENTO DEI DATI  A parte quanto specificato per i dati di navigazione, l\u2019utente \u00e8 libero di fornire i dati personali riportati nei moduli di richiesta del Doria Grand Hotel o comunque indicati in contatti con l\u2019Ufficio per effettuare delle prenotazioni on line, sollecitare l\u2019invio di materiale informativo o di altre comunicazioni. Il loro mancato conferimento pu\u00f2 comportare l\u2019impossibilit\u00e0 di ottenere quanto richiesto.  MODALITA\u2019 DEL TRATTAMENTO  I dati personali sono trattati con strumenti automatizzati per il tempo strettamente necessario a conseguire gli scopi per cui sono stati raccolti. Specifiche misure di sicurezza sono osservate per prevenire la perdita dei dati, usi illeciti o non corretti ed accessi non autorizzati.  DIRITTI DEGLI INTERESSATI  Come previsto dall\u2019articolo 7 della legge 196\/03 e dal Capo III del GDPR 679\/2016, i soggetti cui si riferiscono i dati personali hanno il diritto di chiedere conferma dell\u2019esistenza di dati che li riguardano e delle logiche di trattamento cui sono sottoposti, il diritto di chiederne l\u2019integrazione, il diritto di opporsi alloro trattamento per motivi legittimi, nonch\u00e9 il diritto di chiederne la rettifica, l\u2019aggiornamento, la cancellazione (Oblio) o il blocco se trattati in violazione della legge, il diritto di ottenere una copia dei dati personali oggetto di trattamento, il diritto alla portabilit\u00e0 dei dati stessi, presentando apposita istanza. Le richieste vanno rivolte a Eurofinanziaria Spa, Viale A Doria,22 \u2013\u00a0 20124 MILANO \u2013 Doria Grand Hotel.  DIRITTO DI RECLAMO  Gli interessati che ritengono che il trattamento dei dati personali a loro riferiti effettuato attraverso questo sito avvenga in violazione di quanto previsto dal Regolamento hanno il diritto di proporre reclamo al Garante, come previsto dall\u2019art. 77 del Regolamento stesso, o di adire le opportune sedi giudiziarie (art. 79 del Regolamento).\u3002","og_url":"https:\/\/www.doriagrandhotel.it\/zh-hans\/%e9%9a%90%e7%a7%81%e6%94%bf%e7%ad%96\/","og_site_name":"Doria Grand Hotel","article_publisher":"https:\/\/www.facebook.com\/Doria-Grand-Hotel-150382741666057\/","article_modified_time":"2024-09-27T12:13:52+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/www.doriagrandhotel.it\/wp-content\/uploads\/sites\/170\/2024\/11\/Doria-Grand-Hotel-Milan-Exterior.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@adihotels","twitter_misc":{"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"8 \u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.doriagrandhotel.it\/zh-hans\/%e9%9a%90%e7%a7%81%e6%94%bf%e7%ad%96\/","url":"https:\/\/www.doriagrandhotel.it\/zh-hans\/%e9%9a%90%e7%a7%81%e6%94%bf%e7%ad%96\/","name":"\u9690\u79c1\u653f\u7b56 - Doria Grand Hotel","isPartOf":{"@id":"https:\/\/www.doriagrandhotel.it\/zh-hans\/#website"},"datePublished":"2024-09-27T12:09:58+00:00","dateModified":"2024-09-27T12:13:52+00:00","description":"INFORMAZIONI SUL TRATTAMENTO DEI DATI PERSONALI degli utenti che consultano il sito web del Doria Grand Hotel di Milano \u00a0 ai sensi dell\u2019articolo 13 del D. Lgs. 196\/03 e del Regolamento (UE) 2016\/679 In questa pagina si descrivono le modalit\u00e0 di gestione del sito in riferimento al trattamento dei dati personali degli utenti che lo consultano ed alla loro riservatezza. Si tratta di un\u2019informativa che \u00e8 resa anche ai sensi dell\u2019art. 13 del D. Lgs. n. 196\/2003 e del Regolamento Europeo 679\/2016 \u2013 normativa in materia di Protezione dei Dati Personali, a coloro che interagiscono con i servizi web del Doria Grand Hotel di Milano, accessibili per via telematica a partire dall\u2019indirizzo: www.doriagrandhotel.it corrispondente alla pagina iniziale del sito Doria Grand Hotel, Viale Andrea Doria 22, 20124 Milano L\u2019informativa \u00e8 resa solo per il presente sito e non anche per altri siti web eventualmente consultati dall\u2019utente tramite link. IL \u201cTITOLARE\u201d DEL TRATTAMENTO A seguito della consultazione di questo sito possono essere trattati dati relativi a persone identificate o identificabili. \u201cTitolari del trattamento dei dati personali\u201d eventualmente trattati a seguito della consultazione del nostro sito e di ogni altro dato utilizzato per la fornitura dei nostri servizi, sono Eurofinanziaria Spa, Viale A. Doria, 22 \u2013 20124 Milano per i dati trattati dal Doria Grand Hotel Viale A. Doria, 22 \u2013 20124 Milano LUOGO DI TRATTAMENTO DEI DATI I trattamenti connessi ai servizi web di questo sito [fisicamente posto \u201cin hosting\u201d presso la Fastbooking (\u201cwww.fastbooking.com\u201d)] su server in Irlanda hanno luogo presso la predetta sede e sono curati solo da personale tecnico\u00a0dell\u2019Ufficio incaricato del trattamento, oppure da eventuali incaricati di occasionali operazioni di manutenzione. I dati personali forniti dagli utenti che inoltrano richieste di prenotazione alberghiera o invio di materiale informativo (informazioni, newsletter, registrazioni, ecc.) sono utilizzati al solo fine di eseguire il servizio o la prestazione richiesta e non sono comunicati a terzi, tranne i seguenti possibili casi: \u2022 partners commerciali del Doria Grand Hotel ai quali lo stesso comunica i dati esclusivamente per evadere le prenotazioni on line, tra cui Fastbooking, Tour Sequana, 82 Rue Henri Farman 92130 Issy-les-Moulineaux, France. \u2022 persone societ\u00e0 o studi professionali che prestino attivit\u00e0 di assistenza e consulenza al Doria Grand Hotel in materia contabile, amministrativa, legale, tributaria e finanziaria; \u2022 soggetti cui la facolt\u00e0 di accedere ai dati sia riconosciuta da disposizioni di legge o da ordini delle autorit\u00e0; TIPI DI DATI TRATTATI Dati di navigazione I sistemi informatici e le procedure software preposte al funzionamento di questo sito web acquisiscono, nel corso del loro normale esercizio, alcuni dati personali la cui trasmissione \u00e8 implicita nell\u2019uso dei protocolli di comunicazione di Internet. Si tratta di informazioni che non sono raccolte per essere associate a interessati identificati, ma che per loro stessa natura potrebbero, attraverso elaborazioni ed associazioni con dati detenuti da terzi, permettere di identificare gli utenti. In questa categoria di dati rientrano gli indirizzi IP o i nomi a dominio dei computer utilizzati dagli utenti che si connettono al sito, gli indirizzi in notazione URI (Uniform Resource Identifier) delle risorse richieste, l\u2019orario della richiesta, il metodo utilizzato nel sottoporre la richiesta al server, la dimensione del file ottenuto in risposta, il codice numerico indicante lo stato della risposta data dal server (buon fine, errore, ecc.) ed altri parametri relativi al sistema operativo e all\u2019ambiente informatico dell\u2019utente. Questi dati vengono utilizzati al solo fine di ricavare informazioni statistiche anonime sull\u2019uso del sito e per controllarne il corretto funzionamento e vengono cancellati immediatamente dopo l\u2019elaborazione. I dati potrebbero essere utilizzati per l\u2019accertamento di responsabilit\u00e0 in caso di ipotetici reati informatici ai danni del sito: salva questa eventualit\u00e0, allo stato i dati sui contatti web non persistono per pi\u00f9 di sette giorni. Dati forniti volontariamente dall\u2019utente L\u2019invio facoltativo, esplicito e volontario di posta elettronica agli indirizzi indicati su questo sito comporta la successiva acquisizione dell\u2019indirizzo del mittente, necessario per rispondere alle richieste, nonch\u00e9 degli eventuali altri dati personali inseriti nella missiva. I dati saranno conservati solamente per l\u2019iscrizione richiesta all\u2019invio di newsletter o offerte speciali e non saranno comunicati a nessuno. Non si raccolgono n\u00e9 utilizzano le informazioni personali relative a chi visita il sito Web. I visitatori rimangono anonimi. L\u2019unica eccezione riguarda le informazioni per l\u2019identificazione personale necessarie per ottemperare agli obblighi contrattuali di prenotazione nei confronti dell\u2019utente. Prenotazioni In caso di prenotazione sul sito Web, l\u2019utente \u00e8 tenuto a fornire il proprio nome, indirizzo per la fatturazione, indirizzo e-mail e informazioni sulle modalit\u00e0 di pagamento e sulla carta di credito. I titolari del trattamento utilizzeranno tali informazioni soltanto per l\u2019elaborazione della prenotazione e per inviare informazioni specifiche rilevanti per la conferma della stessa, come la ricevuta, il codice di prenotazione e le condizioni. Le informazioni fornite non verranno utilizzate a fini commerciali e non verranno vendute, trasmesse, concesse in licenza o inoltrate a terzi in altro modo, ad eccezione del nostro fornitore di servizi di prenotazione Fastbooking per esclusive finalit\u00e0 di prenotazione In ogni caso l\u2019amministratore del sito assicura l\u2019adozione di scrupolose procedure per proteggere i dati di navigazione e l\u2019utilizzo di particolari cure per proteggere i dati relativi alla carta di credito forniti in occasione delle prenotazioni on line. Gestione Dati Personali Raccolti da Curriculum Vitae Personali Il Doria Grand Hotel accetta i Curriculum Vitae personali di eventuali candidati via mail in formato elettronico. L\u2019invio spontaneo e volontario del Curriculum sar\u00e0 considerato implicitamente quale consenso informato dalla presente rilasciato dall\u2019interessato alla ricezione ed al trattamento dei dati personali ivi riportati seguendo esclusivamente la finalit\u00e0 legata alla selezione dei potenziali candidati. I dati trattati al fine della selezione dei candidati sono di tipo personale utile alla ricerca del particolare profilo richiesto. In generale la natura dei dati personali \u00e8 di tipo normale, tranne in alcuni eventuali casi ove si possono indicare dati sensibili necessari all\u2019individuazione di particolari requisiti previsti dalle normative in vigore, come l\u2019indicazione a particolari categorie protette, l\u2019idoneit\u00e0 a determinati lavori e\/o avviamenti obbligatori, nel rispetto dei limiti indicati dalle Autorizzazioni Generali del Garante n. 1 e 2 del 15 dicembre 2016 (Reg. Provv. n. 523 del 15 dicembre 2016 Pubblicato sulla Gazzetta Ufficiale n. 303 del 29 dicembre 2016); Il conferimento dei dati relativo alla selezione dei candidati \u00e8 obbligatorio. L\u2019eventuale rifiuto di fornire tali dati comporta l\u2019impossibilit\u00e0 di effettuare una regolare attivit\u00e0 di selezione e la eventuale assunzione. I dati in argomento non saranno comunicati a nessuno. Norme Generali per l\u2019invio del Curriculum Vitae Gli eventuali Curriculum Vitae ricevuti spontaneamente, in risposta ad un annuncio oppure ad una Nostra richiesta verranno archiviati direttamente da appositi incaricati del trattamento dati personali secondo le direttive di sicurezza dei dati personali adottate nel rispetto delle misure minime di sicurezza di cui al Capitolo V Capo I e II del Codice 196\/03 e del Capo IV Sez 2 del RGPD 679\/2016. Questi verranno stampati solo in occasione di un incontro e colloquio con l\u2019interessato. Dopo il colloquio di lavoro, se il candidato non sar\u00e0 selezionato, il CV sar\u00e0 cancellato e\/o distrutto. In tutti gli altri casi, trascorso un periodo di tempo breve e dopo aver effettuato i colloqui ed aver superato il periodo di prova, (60 gg )\u00a0 i C.V. vengono cancellati dal computer e se gi\u00e0 stampati vengono distrutti. Per l\u2019invio dei Curriculum Vitae utilizzare solo i seguenti indirizzi e-mail: amministrazione@doriagrandhotel.it \u2013 c.a. Responsabile del personale PERIODO DI CONSERVAZIONE DEI DATI O CRITERI PER DETERMINARE IL PERIODO Nel rispetto di quanto previsto dall\u2019art. 5 comma 1 lett. e) del Reg. UE 2016\/679 i dati personali raccolti verranno conservati in una forma che consenta l\u2019identificazione degli interessati per un arco di tempo non superiore al conseguimento delle finalit\u00e0 per le quali i dati personali sono trattati. I tempi di conservazione dei dati di natura personale forniti tramite il sito web dipendono dalla finalit\u00e0 del trattamento effettuato, in particolare: \u2022 finalit\u00e0 relative ai dati tecnici di navigazione per il corretto funzionamento del sito web: conservazione solo per la relativa sessione, al termine della quale i dati vengono cancellati; \u2022 finalit\u00e0 di riscontro alla richiesta di informazioni\/fornitura di servizi richiesti (massimo 12 mesi per richiesta di contatto; 10 anni per la eventuale documentazione amministrativo\/contabile\/finanziaria relativa alla fornitura di un servizio); \u2022 raccolta dati per selezione del personale (massimo 24 mesi); \u2022 newsletter, marketing o comunicazioni promozionali in genere via e-mail (fino a revoca del consenso); \u2022 finalit\u00e0 di gestione amministrativa-contabile: 10 anni come da termini di legge per la conservazione della documentazione amministrativo\/contabile\/finanziaria. COOKIES Nessun dato personale degli utenti viene in proposito acquisito dal sito. Non viene fatto uso di cookies per la trasmissione di informazioni di carattere personale, n\u00e9 vengono utilizzati c.d. cookies persistenti di alcun tipo, ovvero sistemi per il tracciamento degli utenti. L\u2019uso di c.d. cookies di sessione (che non vengono memorizzati in modo persistente sul computer dell\u2019utente e svaniscono con la chiusura del browser) \u00e8 strettamente limitato alla trasmissione di identificativi di sessione (costituiti da numeri casuali generati dal server) necessari per consentire l\u2019esplorazione sicura ed efficiente del sito. I c.d. cookies di sessione utilizzati in questo sito evitano il ricorso ad altre tecniche informatiche potenzialmente pregiudizievoli per la riservatezza della navigazione degli utenti e non consentono l\u2019acquisizione di dati personali identificativi dell\u2019utente. FACOLTATIVITA\u2019 DEL CONFERIMENTO DEI DATI A parte quanto specificato per i dati di navigazione, l\u2019utente \u00e8 libero di fornire i dati personali riportati nei moduli di richiesta del Doria Grand Hotel o comunque indicati in contatti con l\u2019Ufficio per effettuare delle prenotazioni on line, sollecitare l\u2019invio di materiale informativo o di altre comunicazioni. Il loro mancato conferimento pu\u00f2 comportare l\u2019impossibilit\u00e0 di ottenere quanto richiesto. MODALITA\u2019 DEL TRATTAMENTO I dati personali sono trattati con strumenti automatizzati per il tempo strettamente necessario a conseguire gli scopi per cui sono stati raccolti. Specifiche misure di sicurezza sono osservate per prevenire la perdita dei dati, usi illeciti o non corretti ed accessi non autorizzati. DIRITTI DEGLI INTERESSATI Come previsto dall\u2019articolo 7 della legge 196\/03 e dal Capo III del GDPR 679\/2016, i soggetti cui si riferiscono i dati personali hanno il diritto di chiedere conferma dell\u2019esistenza di dati che li riguardano e delle logiche di trattamento cui sono sottoposti, il diritto di chiederne l\u2019integrazione, il diritto di opporsi alloro trattamento per motivi legittimi, nonch\u00e9 il diritto di chiederne la rettifica, l\u2019aggiornamento, la cancellazione (Oblio) o il blocco se trattati in violazione della legge, il diritto di ottenere una copia dei dati personali oggetto di trattamento, il diritto alla portabilit\u00e0 dei dati stessi, presentando apposita istanza. Le richieste vanno rivolte a Eurofinanziaria Spa, Viale A Doria,22 \u2013\u00a0 20124 MILANO \u2013 Doria Grand Hotel. DIRITTO DI RECLAMO Gli interessati che ritengono che il trattamento dei dati personali a loro riferiti effettuato attraverso questo sito avvenga in violazione di quanto previsto dal Regolamento hanno il diritto di proporre reclamo al Garante, come previsto dall\u2019art. 77 del Regolamento stesso, o di adire le opportune sedi giudiziarie (art. 79 del Regolamento).\u3002","breadcrumb":{"@id":"https:\/\/www.doriagrandhotel.it\/zh-hans\/%e9%9a%90%e7%a7%81%e6%94%bf%e7%ad%96\/#breadcrumb"},"inLanguage":"zh-CN","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.doriagrandhotel.it\/zh-hans\/%e9%9a%90%e7%a7%81%e6%94%bf%e7%ad%96\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.doriagrandhotel.it\/zh-hans\/%e9%9a%90%e7%a7%81%e6%94%bf%e7%ad%96\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.doriagrandhotel.it\/zh-hans\/%e6%ac%a2%e8%bf%8e%e6%9d%a5%e5%88%b0%e5%a4%9a%e9%87%8c%e4%ba%9a%e5%a4%a7%e9%85%92%e5%ba%97\/"},{"@type":"ListItem","position":2,"name":"\u9690\u79c1\u653f\u7b56"}]},{"@type":"WebSite","@id":"https:\/\/www.doriagrandhotel.it\/zh-hans\/#website","url":"https:\/\/www.doriagrandhotel.it\/zh-hans\/","name":"Doria Grand Hotel","description":"Official website of Doria Grand Hotel , a luxury  hotel in Milan center. Book your hotel in Milan at the best price","publisher":{"@id":"https:\/\/www.doriagrandhotel.it\/zh-hans\/#organization"},"alternateName":"Doria Grand Hotel","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.doriagrandhotel.it\/zh-hans\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-CN"},{"@type":"Organization","@id":"https:\/\/www.doriagrandhotel.it\/zh-hans\/#organization","name":"Doria Grand Hotel","alternateName":"Doria Grand Hotel","url":"https:\/\/www.doriagrandhotel.it\/zh-hans\/","logo":{"@type":"ImageObject","inLanguage":"zh-CN","@id":"https:\/\/www.doriagrandhotel.it\/zh-hans\/#\/schema\/logo\/image\/","url":"https:\/\/doria-grand-hotel.ms2.decms.eu\/wp-content\/uploads\/sites\/170\/2024\/09\/LOGO-DGH-tr.png","contentUrl":"https:\/\/doria-grand-hotel.ms2.decms.eu\/wp-content\/uploads\/sites\/170\/2024\/09\/LOGO-DGH-tr.png","width":230,"height":51,"caption":"Doria Grand Hotel"},"image":{"@id":"https:\/\/www.doriagrandhotel.it\/zh-hans\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Doria-Grand-Hotel-150382741666057\/","https:\/\/x.com\/adihotels","https:\/\/www.instagram.com\/doriagrandhotel\/?hl=en","https:\/\/www.linkedin.com\/company\/doria-grand-hotel\/","https:\/\/www.tripadvisor.com\/Hotel_Review-g187849-d202862-Reviews-Doria_Grand_Hotel-Milan_Lombardy.html"]}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.doriagrandhotel.it\/zh-hans\/wp-json\/wp\/v2\/pages\/63","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.doriagrandhotel.it\/zh-hans\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.doriagrandhotel.it\/zh-hans\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.doriagrandhotel.it\/zh-hans\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.doriagrandhotel.it\/zh-hans\/wp-json\/wp\/v2\/comments?post=63"}],"version-history":[{"count":0,"href":"https:\/\/www.doriagrandhotel.it\/zh-hans\/wp-json\/wp\/v2\/pages\/63\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.doriagrandhotel.it\/zh-hans\/wp-json\/wp\/v2\/media?parent=63"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}